{"id":1201,"date":"2023-10-10T16:18:08","date_gmt":"2023-10-10T19:18:08","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=1201"},"modified":"2023-10-10T16:19:18","modified_gmt":"2023-10-10T19:19:18","slug":"stj-agente-publico-pode-ser-acionado-diretamente-ao-incorrer-em-abuso-de-direito-quando-excede-suas-prerrogativas","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-agente-publico-pode-ser-acionado-diretamente-ao-incorrer-em-abuso-de-direito-quando-excede-suas-prerrogativas\/","title":{"rendered":"STJ: Agente p\u00fablico pode ser acionado diretamente ao incorrer em abuso de direito quando excede suas prerrogativas"},"content":{"rendered":"<p><strong>Por:<\/strong> Andr\u00e9 Luciano Vicente da Silva<\/p>\n<p>Segundo decis\u00e3o da Quarta Turma do Superior Tribunal de Justi\u00e7a (STJ), no Recurso Especial n\u00ba 1.842.613, o ex-Procurador da Rep\u00fablica, Deltan Dallagnol, praticou excessos na entrevista coletiva concedida em 2016, na qual fez uso do programa de PowerPoint para expor a den\u00fancia apresentada em face do, \u00e0 \u00e9poca, ex-Presidente Lula, na opera\u00e7\u00e3o Lava Jato. Deltan foi condenado ao pagamento de indeniza\u00e7\u00e3o, por danos morais, no importe de R$ 75.000,00 (setenta e cinco mil reais), em favor de Lula.<\/p>\n<p><strong>Relat\u00f3rio do Caso<\/strong><\/p>\n<p>LUIZ IN\u00c1CIO LULA DA SILVA (autor) ajuizou a\u00e7\u00e3o de repara\u00e7\u00e3o de danos morais em face de DELTAN MARTINAZZO DALLAGNOL (r\u00e9u), em virtude da realiza\u00e7\u00e3o de entrevista coletiva de imprensa, transmitida em rede nacional, cujo pretexto seria informar a apresenta\u00e7\u00e3o de den\u00fancia criminal contra o autor por suposta pr\u00e1tica de corrup\u00e7\u00e3o passiva \u2013 entre outros delitos \u2013 e por ter recebido, em contrapartida, um im\u00f3vel <em>triplex<\/em> no Guaruj\u00e1.<\/p>\n<p>Sustenta o autor que o r\u00e9u se manifestou, durante a apresenta\u00e7\u00e3o, com adjetiva\u00e7\u00f5es negativas, incompat\u00edvel com a dignidade da pessoa humana, com a garantia constitucional da presun\u00e7\u00e3o da inoc\u00eancia e com o devido processo legal, com o claro prop\u00f3sito de causar ataques a sua honra, imagem e reputa\u00e7\u00e3o, agindo com evidente abuso de direito. Assim, Deltan cometeu il\u00edcito pass\u00edvel de repara\u00e7\u00e3o pelos danos morais, requerendo a condena\u00e7\u00e3o de indeniza\u00e7\u00e3o no valor de R$ 1.000.000,00 (um milh\u00e3o de reais).<\/p>\n<p>Em contesta\u00e7\u00e3o, Deltan alegou, preliminarmente, ilegitimidade de parte, sob o argumento de que a a\u00e7\u00e3o de indeniza\u00e7\u00e3o por danos causados pelo agente p\u00fablico a terceiros deve ser imposta em face da pessoa jur\u00eddica de direito p\u00fablico da qual fa\u00e7a parte o agente, no caso o Minist\u00e9rio P\u00fablico Federal.<\/p>\n<p>Quanto ao m\u00e9rito, o r\u00e9u sustentou que, regularmente designado para compor a for\u00e7a-tarefa da denominada &#8220;Opera\u00e7\u00e3o Lava Jato&#8221;, tendo em vista a gravidade dos fatos averiguados nas investiga\u00e7\u00f5es e, ainda, por ter Lula ocupado o cargo de Presidente da Rep\u00fablica, Deltan foi compelido a conferir publicidade \u00e0s informa\u00e7\u00f5es obtidas quando j\u00e1 reunidos elementos de prova suficientes \u00e0 propositura da a\u00e7\u00e3o penal.<\/p>\n<p>O ex-Procurador afirmou que se valeu dos meios necess\u00e1rios, de forma did\u00e1tica, para narrar com isen\u00e7\u00e3o os fatos oriundos da investiga\u00e7\u00e3o e expostos na den\u00fancia. Acrescentou que a divulga\u00e7\u00e3o da den\u00fancia foi considerada regular pela Corregedoria do Minist\u00e9rio P\u00fablico Federal e pelo Conselho Nacional do Minist\u00e9rio P\u00fablico.<\/p>\n<p>A primeira inst\u00e2ncia julgou improcedente o pedido indenizat\u00f3rio, ent\u00e3o, Lula interp\u00f4s apela\u00e7\u00e3o, apreciada pelo Tribunal de Justi\u00e7a do Estado de S\u00e3o Paulo, que tamb\u00e9m lhe negou provimento, subindo seu recurso para o Superior Tribunal de Justi\u00e7a, que reformou a senten\u00e7a, no sentido de dar provimento ao pleito, condenando Dallagnol, ao final, a indenizar Lula em R$ 75.000,00.<\/p>\n<p><strong>Pol\u00eamica que envolve a decis\u00e3o<\/strong><\/p>\n<p>A Constitui\u00e7\u00e3o\/88, prev\u00ea no 6\u00ba par\u00e1grafo de seu 37\u00ba artigo:<\/p>\n<p>As pessoas jur\u00eddicas de direito p\u00fablico e as de direito privado prestadoras de servi\u00e7os p\u00fablicos responder\u00e3o pelos danos que seus agentes, nessa qualidade, causarem a terceiros, assegurado o direito de regresso contra o respons\u00e1vel nos casos de dolo ou culpa.<\/p>\n<p>A ideia por tr\u00e1s desse disposto, pelo constituinte origin\u00e1rio, era a de que a pessoa jur\u00eddica, seja da administra\u00e7\u00e3o direta, indireta ou prestadora de servi\u00e7o p\u00fablico, se responsabilizaria, primariamente, quanto aos poss\u00edveis danos causados por seus agentes a terceiros, e, ao mesmo tempo, garantiria que em casos de dolo ou culpa, ap\u00f3s a repara\u00e7\u00e3o do dano pela primeira parte, caberia a\u00e7\u00e3o regressiva em face do agente p\u00fablico. Esta garantia visava proteger duplamente tanto o agente, no desempenho de sua fun\u00e7\u00e3o, quanto a administra\u00e7\u00e3o, haja vista o direito de a\u00e7\u00e3o de regresso.<\/p>\n<p>Em 2019, o STF em concord\u00e2ncia com esse entendimento, atrav\u00e9s do Recurso Especial 1027633\/SP, anuiu quanto \u00e0 impossibilidade de o terceiro prejudicado acionar diretamente a pessoa f\u00edsica do agente p\u00fablico nas a\u00e7\u00f5es regulares de seu servi\u00e7o, em virtude da dupla garantia prestada no Art. 37, \u00a76\u00ba da Carta Magna.<\/p>\n<p>Entretanto, muito recentemente e por motivos diversos, principalmente motivos pol\u00edticos e midi\u00e1ticos, envolvendo o caso, o STJ em maio de 2022 resolveu dar um novo entendimento a esse dispositivo legal. Trata-se do RE 1842613\/SP, interposto por Lula. Na ocasi\u00e3o, o STJ se aproveitou de uma brecha de interpreta\u00e7\u00e3o do RE 1027633\/SP, do STF de 2019, quando este discorre sobre \u201cfun\u00e7\u00f5es p\u00fablicas regulares\u201d, dando a seguinte leitura:<\/p>\n<p>Nas situa\u00e7\u00f5es em que o dano causado ao particular \u00e9 provocado por conduta irregular do agente p\u00fablico, compreendendo-se &#8220;irregular&#8221; como conduta estranha ao rol das atribui\u00e7\u00f5es funcionais, a a\u00e7\u00e3o indenizat\u00f3ria cujo objeto seja a pr\u00e1tica do abuso de direito que culminou em dano pode ser ajuizada em face do pr\u00f3prio agente.<\/p>\n<p>Apesar de, num primeiro momento, a decis\u00e3o ter uma certa base s\u00f3lida, que visa tentar barrar que agentes p\u00fablicos ultrapassem os limites de suas atribui\u00e7\u00f5es e, assim, realizem a\u00e7\u00f5es que n\u00e3o mais seriam consideradas em nome do Estado e, ao faz\u00ea-lo, se causarem dano a terceiro, poder-se-ia pular a etapa de buscar a repara\u00e7\u00e3o frente ao Estado e buscar a repara\u00e7\u00e3o contra a pr\u00f3pria pessoa f\u00edsica causadora do dano, tamb\u00e9m se criou uma brecha que abre interpreta\u00e7\u00f5es divergentes quanto ao direito garantido pelo par\u00e1grafo 6\u00ba do Art. 37 da CF\/88.<\/p>\n<p>Destaca-se a pr\u00f3pria controv\u00e9rsia entre as inst\u00e2ncias superiores sobre o mesmo assunto. Enquanto uma (STF) disp\u00f4s que, pelo princ\u00edpio da dupla garantia o Estado sempre seria o acionado para reparar este tipo de dano e se necess\u00e1rio buscaria a repara\u00e7\u00e3o administrativa posteriormente quanto ao agente, a outra (STJ) abriu a brecha para que existam casos em que o terceiro prejudicado v\u00e1 diretamente buscar a repara\u00e7\u00e3o frente \u00e0 pessoa f\u00edsica do agente p\u00fablico causador do dano.<\/p>\n<p>Ademais, h\u00e1 de se destacar a possibilidade de que sempre que haja um dano causado por um agente p\u00fablico, primeiro se investigar\u00e1 se este estava agindo com conduta dita regular ou irregular para, ent\u00e3o, ver qual o polo passivo da a\u00e7\u00e3o de repara\u00e7\u00e3o de dano que venha a propor o terceiro.<\/p>\n<p><strong>PROCESSO RELACIONADO<\/strong>: Recurso Especial n\u00ba 1.842.613<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Andr\u00e9 Luciano Vicente da Silva Segundo decis\u00e3o da Quarta Turma do Superior Tribunal de Justi\u00e7a (STJ), no Recurso Especial n\u00ba 1.842.613, o ex-Procurador da Rep\u00fablica, Deltan Dallagnol, praticou excessos na entrevista coletiva concedida em 2016, na qual fez uso do programa de PowerPoint para expor a den\u00fancia apresentada em face do, \u00e0 \u00e9poca, ex-Presidente [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":1046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[121,84,687,30],"coauthors":[],"class_list":["post-1201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-danos-morais","tag-responsabilidade-civil","tag-servidor-publico","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=1201"}],"version-history":[{"count":3,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1201\/revisions"}],"predecessor-version":[{"id":1204,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1201\/revisions\/1204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/1046"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=1201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=1201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=1201"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=1201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}