{"id":1229,"date":"2023-10-31T16:38:06","date_gmt":"2023-10-31T19:38:06","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=1229"},"modified":"2023-10-31T16:38:06","modified_gmt":"2023-10-31T19:38:06","slug":"reclamacao-constitucional-e-a-liberdade-de-imprensa-a-decisao-do-stf-na-defesa-da-informacao-e-dos-direitos-fundamentais","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/reclamacao-constitucional-e-a-liberdade-de-imprensa-a-decisao-do-stf-na-defesa-da-informacao-e-dos-direitos-fundamentais\/","title":{"rendered":"Reclama\u00e7\u00e3o Constitucional e a Liberdade de Imprensa: A Decis\u00e3o do STF na Defesa da Informa\u00e7\u00e3o e dos Direitos Fundamentais"},"content":{"rendered":"<p><strong>Por:<\/strong> Amanda Antkiewicz<\/p>\n<p><strong>ELUCIDA\u00c7\u00c3O DO TEMA<\/strong><\/p>\n<p>A Editora Alvenegra LTDA prop\u00f4s uma reclama\u00e7\u00e3o constitucional perante o Supremo Tribunal Federal (STF) contra a decis\u00e3o proferida pelo Ju\u00edzo da 21\u00aa Vara C\u00edvel de Bras\u00edlia-DF. Essa decis\u00e3o determinava o recolhimento de todos os exemplares f\u00edsicos da edi\u00e7\u00e3o n\u00ba 201 da Revista Piau\u00ed, distribu\u00edda em todo o territ\u00f3rio nacional, e a remo\u00e7\u00e3o do conte\u00fado correspondente veiculado em sites de internet.<\/p>\n<p>Em s\u00edntese, a reclamante alega que a senten\u00e7a do ju\u00edzo reclamado, assim como a manuten\u00e7\u00e3o da decis\u00e3o no agravo anteriormente interposto, viola os princ\u00edpios constitucionais relacionados \u00e0 liberdade de imprensa. Alega que estava apenas exercendo seu trabalho com respaldo nos artigos 5\u00ba, IV, IX e XIV da Constitui\u00e7\u00e3o Federal\/88, sem prejudicar os benefici\u00e1rios da a\u00e7\u00e3o. Portanto, a \u00fanica alternativa foi apresentar a reclama\u00e7\u00e3o ora em an\u00e1lise, a fim de requerer a cassa\u00e7\u00e3o da decis\u00e3o para que outra seja proferida em conformidade com o decidido por esta Suprema Corte na ADPF 130\/DF.<\/p>\n<p>A reclamante tamb\u00e9m solicita, preliminarmente, a concess\u00e3o da antecipa\u00e7\u00e3o dos efeitos da tutela pretendida, argumentando que os custos decorrentes da medida arbitr\u00e1ria imposta pelo ju\u00edzo da 21\u00aa Vara C\u00edvel de Bras\u00edlia-DF s\u00e3o astron\u00f4micos e que a informa\u00e7\u00e3o perder\u00e1 seu fator de atualidade.<\/p>\n<p><strong>DA DECIS\u00c3O FINAL E SEUS FUNDAMENTOS.<\/strong><\/p>\n<p>Com rela\u00e7\u00e3o ao pedido da tutela de urg\u00eancia, o relator analisou os requisitos previstos no art. 300 do C\u00f3digo de Processo Civil e, considerando que a disputa envolve os limites da liberdade de express\u00e3o e manifesta\u00e7\u00e3o, esclarece que n\u00e3o se admite controle pr\u00e9vio do conte\u00fado difundido pelos meios de comunica\u00e7\u00e3o social, exceto em casos de abuso ou m\u00e1-f\u00e9. O relator entende que antecipar a tutela para evitar novas manifesta\u00e7\u00f5es que possam ofender a honra do autor representaria, em \u00faltima an\u00e1lise, censura pr\u00e9via e gen\u00e9rica de conte\u00fado, o que n\u00e3o encontra amparo na legisla\u00e7\u00e3o.<\/p>\n<p>O relator tamb\u00e9m considera plaus\u00edvel o argumento dos benefici\u00e1rios em rela\u00e7\u00e3o \u00e0 viola\u00e7\u00e3o do direito \u00e0 imagem e \u00e0 honra, dada a perman\u00eancia dos conte\u00fados da forma como foram divulgados. Portanto, julgou parcialmente procedente o pedido preliminar da tutela antecipada, determinando que a Editora remova os nomes das partes autoras em at\u00e9 15 dias, sob pena de multa di\u00e1ria no valor de R$ 10.000,00 (dez mil reais), com um limite de dez dias.<\/p>\n<p>No que diz respeito ao m\u00e9rito da quest\u00e3o, o ministro observa que a parte reclamada n\u00e3o demonstrou explicitamente como o conte\u00fado jornal\u00edstico teria incorrido em abuso ou m\u00e1-f\u00e9 no direito de informar, colocando a liberdade de imprensa em segundo plano e invertendo o regime de prioridade estabelecido no Ac\u00f3rd\u00e3o da ADPF 130\/DF.<\/p>\n<p>Portanto, conclui que n\u00e3o \u00e9 cab\u00edvel uma medida judicial que imponha o recolhimento imediato de todos os exemplares f\u00edsicos de uma edi\u00e7\u00e3o de uma revista de alcance nacional. No caso espec\u00edfico, n\u00e3o existem motivos para afastar essa regra geral. Diante disso, o Supremo Tribunal Federal julgou procedente o pedido para cassar a decis\u00e3o reclamada e determinar a observ\u00e2ncia do entendimento firmado na ADPF 130\/DF, qual seja, o respeito \u00e0 liberdade de imprensa e \u00e0 veicula\u00e7\u00e3o da informa\u00e7\u00e3o.<\/p>\n<p><strong>PROCESSO RELACIONADO:<\/strong> ADPF 130\/DF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Amanda Antkiewicz ELUCIDA\u00c7\u00c3O DO TEMA A Editora Alvenegra LTDA prop\u00f4s uma reclama\u00e7\u00e3o constitucional perante o Supremo Tribunal Federal (STF) contra a decis\u00e3o proferida pelo Ju\u00edzo da 21\u00aa Vara C\u00edvel de Bras\u00edlia-DF. Essa decis\u00e3o determinava o recolhimento de todos os exemplares f\u00edsicos da edi\u00e7\u00e3o n\u00ba 201 da Revista Piau\u00ed, distribu\u00edda em todo o territ\u00f3rio nacional, [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":785,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[707,706,6],"coauthors":[],"class_list":["post-1229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-liberdade-de-imprensa","tag-reclamacao-constitucional","tag-stf"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=1229"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1229\/revisions"}],"predecessor-version":[{"id":1230,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1229\/revisions\/1230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/785"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=1229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=1229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=1229"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=1229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}