{"id":1514,"date":"2025-04-16T12:17:02","date_gmt":"2025-04-16T15:17:02","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=1514"},"modified":"2025-04-16T12:17:02","modified_gmt":"2025-04-16T15:17:02","slug":"stj-e-devido-indenizacao-e-pensao-vitalicia-a-participante-de-estudo-clinico-que-ficou-com-sequelas","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-e-devido-indenizacao-e-pensao-vitalicia-a-participante-de-estudo-clinico-que-ficou-com-sequelas\/","title":{"rendered":"STJ: \u00c9 devido indeniza\u00e7\u00e3o e pens\u00e3o vital\u00edcia a participante de estudo cl\u00ednico que ficou com sequelas"},"content":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ), por unanimidade, confirmou a condena\u00e7\u00e3o de um laborat\u00f3rio a pagar R$ 300 mil de indeniza\u00e7\u00e3o para a participante de uma pesquisa cl\u00ednica que desenvolveu doen\u00e7a dermatol\u00f3gica rara e incapacitante.<\/p>\n<p>A mulher relatou os primeiros sinais da doen\u00e7a dez dias ap\u00f3s a segunda rodada de aplica\u00e7\u00e3o do medicamento drospirenona + etinilestradiol, uma formula\u00e7\u00e3o amplamente utilizada em anticoncepcionais orais. O estudo visava avaliar a biodisponibilidade e a efic\u00e1cia de um medicamento similar, que seria lan\u00e7ado pelo laborat\u00f3rio. Diante dos problemas verificados, ela acionou a Justi\u00e7a para obter o custeio integral dos tratamentos dermatol\u00f3gico, psicol\u00f3gico e psiqui\u00e1trico, al\u00e9m de indeniza\u00e7\u00f5es por danos morais, est\u00e9ticos e psicol\u00f3gicos.<\/p>\n<p>O Tribunal de Justi\u00e7a de Goi\u00e1s (TJGO) reconheceu o <span class=\"termo-glossario\" data-match=\"nexo causal\" data-termo=\"Nexo causal\" data-significado=\"V\u00ednculo que estabelece uma rela\u00e7\u00e3o de causa e consequ\u00eancia entre dois fatos.\">nexo causal<\/span> entre o uso do medicamento e o surgimento da doen\u00e7a e condenou o laborat\u00f3rio a indenizar a v\u00edtima em R$ 300 mil, al\u00e9m de pagar pens\u00e3o vital\u00edcia de cinco sal\u00e1rios m\u00ednimos devido \u00e0 redu\u00e7\u00e3o da capacidade de trabalho causada pelas sequelas irrevers\u00edveis.<\/p>\n<p>Ao STJ, o laborat\u00f3rio alegou que o TJGO inverteu indevidamente o \u00f4nus da prova, exigindo a produ\u00e7\u00e3o de uma prova negativa, o que seria imposs\u00edvel. Al\u00e9m disso, argumentou que os valores da condena\u00e7\u00e3o deveriam ser reduzidos, pois a renda da v\u00edtima era inferior a um sal\u00e1rio m\u00ednimo antes da pesquisa, e a manuten\u00e7\u00e3o integral da decis\u00e3o do TJGO representaria enriquecimento il\u00edcito, contrariando a pr\u00f3pria jurisprud\u00eancia do STJ.<\/p>\n<p><strong>Pesquisas com seres humanos devem garantir condi\u00e7\u00f5es de tratamento<\/strong><\/p>\n<p>A relatora do recurso, ministra Nancy Andrighi, afirmou que a fragilidade da per\u00edcia realizada impediu a confirma\u00e7\u00e3o, com grau de certeza, do <span class=\"termo-intermed\" data-match=\"nexo causal\">nexo causal<\/span> entre a administra\u00e7\u00e3o do medicamento e o desenvolvimento da doen\u00e7a. No entanto, a ministra enfatizou que o TJGO, ao considerar outros elementos que endossavam as alega\u00e7\u00f5es da v\u00edtima, atribuiu ao laborat\u00f3rio o risco pelo insucesso da per\u00edcia, determinando que arcasse com as consequ\u00eancias de n\u00e3o ter demonstrado a inexist\u00eancia do <span class=\"termo-intermed\" data-match=\"nexo causal\">nexo causal<\/span> \u2013 prova que lhe seria favor\u00e1vel, conforme a dimens\u00e3o objetiva do \u00f4nus da prova.<\/p>\n<p>Al\u00e9m disso, a ministra destacou que a <a href=\"https:\/\/bvsms.saude.gov.br\/bvs\/saudelegis\/anvisa\/2015\/rdc0009_20_02_2015.pdf\">RDC 9\/2015 da Anvisa<\/a>, em seu artigo 12, estabelece que o patrocinador \u00e9 respons\u00e1vel por todas as despesas necess\u00e1rias para a resolu\u00e7\u00e3o de eventos adversos decorrentes do estudo cl\u00ednico, como exames, tratamentos e interna\u00e7\u00e3o.<\/p>\n<p>Nancy Andrighi tamb\u00e9m apontou que a <a href=\"https:\/\/www.gov.br\/conselho-nacional-de-saude\/pt-br\/acesso-a-informacao\/legislacao\/resolucoes\/2012\/resolucao-no-466.pdf\/view\">Resolu\u00e7\u00e3o 466\/2012 do Conselho Nacional de Sa\u00fade<\/a> exige que as pesquisas com seres humanos, em qualquer \u00e1rea do conhecimento, garantam acompanhamento, tratamento, assist\u00eancia integral e orienta\u00e7\u00e3o aos participantes, inclusive nas pesquisas de rastreamento. Segundo ela, a resolu\u00e7\u00e3o &#8220;responsabiliza o pesquisador, o patrocinador e as institui\u00e7\u00f5es e\/ou organiza\u00e7\u00f5es envolvidas nas diferentes fases da pesquisa pela assist\u00eancia integral aos participantes, no que se refere \u00e0s complica\u00e7\u00f5es e aos danos decorrentes, prevendo, inclusive, o direito \u00e0 indeniza\u00e7\u00e3o&#8221;.<\/p>\n<p><strong>Reconhecida a incapacidade permanente, \u00e9 devida a pens\u00e3o vital\u00edcia<\/strong><\/p>\n<p>Por fim, a relatora destacou que o pensionamento mensal de cinco sal\u00e1rios m\u00ednimos n\u00e3o configura enriquecimento sem causa, uma vez que, ao determin\u00e1-lo, o TJGO levou em considera\u00e7\u00e3o n\u00e3o apenas a subsist\u00eancia da autora, mas tamb\u00e9m o valor necess\u00e1rio para cobrir os tratamentos m\u00e9dicos exigidos pelo seu quadro.<\/p>\n<p>&#8220;Reconhecida a incapacidade permanente da autora, \u00e9 devido o arbitramento de pens\u00e3o vital\u00edcia em seu favor, segundo a orienta\u00e7\u00e3o jurisprudencial do STJ, n\u00e3o havendo, pois, o limitador da expectativa de vida&#8221;, concluiu ao negar <span class=\"termo-glossario\" data-match=\"provimento\" data-termo=\"Provimento\" data-significado=\"Ato de prover. Dar provimento a recurso significa acolher o pedido para reformar ou anular decis\u00e3o judicial anterior. No direito administrativo, \u00e9 o ato de preencher vaga no servi\u00e7o p\u00fablico.\">provimento<\/span> ao recurso.<\/p>\n<p><strong>PROCESSO RELACIONADO<\/strong>: <a href=\"https:\/\/processo.stj.jus.br\/processo\/julgamento\/eletronico\/documento\/mediado\/?documento_tipo=integra&amp;documento_sequencial=296891064&amp;registro_numero=202401801260&amp;peticao_numero=&amp;publicacao_data=20250225&amp;formato=PDF\">REsp 2.145.132<\/a><\/p>\n<p><strong>FONTE:<\/strong> Com informa\u00e7\u00f5es da Se\u00e7\u00e3o de Comunica\u00e7\u00e3o Social do STJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ), por unanimidade, confirmou a condena\u00e7\u00e3o de um laborat\u00f3rio a pagar R$ 300 mil de indeniza\u00e7\u00e3o para a participante de uma pesquisa cl\u00ednica que desenvolveu doen\u00e7a dermatol\u00f3gica rara e incapacitante. A mulher relatou os primeiros sinais da doen\u00e7a dez dias ap\u00f3s a segunda rodada de aplica\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":1146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[14,27,862,863,30],"coauthors":[],"class_list":["post-1514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-biodireito","tag-direito-civil","tag-estudos-clinicos","tag-laboratorio","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=1514"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1514\/revisions"}],"predecessor-version":[{"id":1515,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1514\/revisions\/1515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/1146"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=1514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=1514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=1514"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=1514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}