{"id":1613,"date":"2026-01-15T11:56:56","date_gmt":"2026-01-15T14:56:56","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=1613"},"modified":"2026-01-15T11:57:21","modified_gmt":"2026-01-15T14:57:21","slug":"stj-nao-cabe-agravo-de-instrumento-contra-decisao-que-autorizou-producao-de-prova","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-nao-cabe-agravo-de-instrumento-contra-decisao-que-autorizou-producao-de-prova\/","title":{"rendered":"STJ &#8211; N\u00e3o cabe agravo de instrumento contra decis\u00e3o que autorizou produ\u00e7\u00e3o de prova"},"content":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) concluiu que a decis\u00e3o que defere a realiza\u00e7\u00e3o de prova pericial n\u00e3o pode ser combatida por meio do recurso de <span class=\"termo-glossario\" data-match=\"agravo de instrumento\" data-termo=\"Agravo de Instrumento\" data-significado=\"Recurso contra decis\u00e3o tomada pelo juiz no curso do processo.\">agravo de instrumento<\/span>.<\/p>\n<p>No curso de um incidente de <span class=\"termo-glossario\" data-match=\"desconsidera\u00e7\u00e3o da personalidade jur\u00eddica\" data-termo=\"Desconsidera\u00e7\u00e3o da personalidade jur\u00eddica\" data-significado=\"Desconsidera\u00e7\u00e3o da personalidade jur\u00eddica \u00e9 o ato judicial que permite que o s\u00f3cio seja cobrado pela d\u00edvida da empresa, arcando com seu patrim\u00f4nio pessoal.\">desconsidera\u00e7\u00e3o da personalidade jur\u00eddica<\/span>, o ju\u00edzo autorizou a produ\u00e7\u00e3o de per\u00edcia, o que resultou na interposi\u00e7\u00e3o de <span class=\"\" data-match=\"agravo de instrumento\">agravo de instrumento<\/span> por uma das partes contra a decis\u00e3o interlocut\u00f3ria.<\/p>\n<p>O Tribunal de Justi\u00e7a de S\u00e3o Paulo (TJSP) considerou que esse tipo de recurso \u00e9 inadmiss\u00edvel em mat\u00e9ria probat\u00f3ria, j\u00e1 que n\u00e3o est\u00e1 listado no rol do <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm#art1015\">artigo 1.015 do C\u00f3digo de Processo Civil (CPC)<\/a>, o qual prev\u00ea as hip\u00f3teses de cabimento do <span class=\"\" data-match=\"agravo de instrumento\">agravo de instrumento<\/span>.<\/p>\n<p>No <span class=\"termo-glossario\" data-match=\"recurso especial\" data-termo=\"Recurso Especial\" data-significado=\"O recurso especial (sigla REsp) \u00e9 dirigido ao STJ para contestar poss\u00edvel m\u00e1 aplica\u00e7\u00e3o da lei federal por um tribunal de segundo grau. Assim, o REsp serve para que o STJ uniformize a interpreta\u00e7\u00e3o da legisla\u00e7\u00e3o federal em todo o pa\u00eds.\">recurso especial<\/span>, a parte recorrente sustentou que o agravo seria cab\u00edvel contra toda decis\u00e3o interlocut\u00f3ria proferida em incidente de <span class=\"\" data-match=\"desconsidera\u00e7\u00e3o da personalidade jur\u00eddica\">desconsidera\u00e7\u00e3o da personalidade jur\u00eddica<\/span>, sem distin\u00e7\u00e3o quanto ao conte\u00fado decis\u00f3rio.<\/p>\n<p><strong>Produ\u00e7\u00e3o de provas n\u00e3o est\u00e1 na previs\u00e3o do artigo 1.015 do CPC<\/strong><\/p>\n<p>O relator, ministro Ricardo Villas B\u00f4as Cueva, afirmou que, apesar do termo utilizado pelo legislador, o incidente de <span class=\"\" data-match=\"desconsidera\u00e7\u00e3o da personalidade jur\u00eddica\">desconsidera\u00e7\u00e3o da personalidade jur\u00eddica<\/span> deve ser visto como uma nova demanda de conhecimento, j\u00e1 que visa atingir terceiro e \u00e9 composta por partes, <span class=\"termo-glossario\" data-match=\"causa de pedir\" data-termo=\"Causa de pedir\" data-significado=\"Conjunto de fatos e fundamentos jur\u00eddicos em que se baseia o pedido numa a\u00e7\u00e3o judicial.\">causa de pedir<\/span> e pedido.<\/p>\n<p>O ministro tamb\u00e9m salientou que, contra decis\u00f5es interlocut\u00f3rias proferidas durante o incidente de desconsidera\u00e7\u00e3o, apenas \u00e9 cab\u00edvel <span class=\"\" data-match=\"agravo de instrumento\">agravo de instrumento<\/span> nos casos estabelecidos no artigo 1.015 do CPC, relativos \u00e0 fase de conhecimento.<\/p>\n<p>De acordo com o relator, as hip\u00f3teses previstas no dispositivo n\u00e3o abrangem o cabimento desse recurso contra decis\u00e3o sobre produ\u00e7\u00e3o probat\u00f3ria. Para ele, \u00e9 inaplic\u00e1vel a exce\u00e7\u00e3o tratada no par\u00e1grafo \u00fanico do mesmo dispositivo, por ser restrita \u00e0s fases de liquida\u00e7\u00e3o e de cumprimento de <span class=\"termo-glossario\" data-match=\"senten\u00e7a\" data-termo=\"Senten\u00e7a\" data-significado=\"Decis\u00e3o do ju\u00edzo de primeiro grau que encerra o processo nessa inst\u00e2ncia.\">senten\u00e7a<\/span> e aos processos de execu\u00e7\u00e3o e de invent\u00e1rio.<\/p>\n<p><strong>Aplica\u00e7\u00e3o da taxatividade mitigada \u00e9 apenas para casos urgentes<\/strong><\/p>\n<p>Villas B\u00f4as Cueva lembrou que o STJ, no <a href=\"https:\/\/processo.stj.jus.br\/repetitivos\/temas_repetitivos\/pesquisa.jsp?novaConsulta=true&amp;tipo_pesquisa=T&amp;cod_tema_inicial=988&amp;cod_tema_final=988\">Tema 988<\/a> dos recursos <span class=\"termo-glossario\" data-match=\"repetitivos\" data-termo=\"Repetitivos\" data-significado=\"Recurso repetitivo \u00e9 um recurso escolhido para ser julgado como representativo de uma quest\u00e3o jur\u00eddica presente em muitos outros processos, para que a tese fixada pelo tribunal seja aplicada na solu\u00e7\u00e3o dos casos semelhantes em todo o pa\u00eds.\">repetitivos<\/span>, mitigou a taxatividade do rol do artigo 1.015 do CPC, quando verificada a urg\u00eancia decorrente da inutilidade do julgamento em momento posterior.<\/p>\n<p>No entanto, no caso em julgamento, o ministro entendeu n\u00e3o ter sido evidenciado o preju\u00edzo irrepar\u00e1vel ou de dif\u00edcil repara\u00e7\u00e3o que o recorrente sofreria se a quest\u00e3o relativa \u00e0 per\u00edcia ficasse para ser apreciada pelo tribunal de segunda inst\u00e2ncia somente no recurso de <span class=\"termo-glossario\" data-match=\"apela\u00e7\u00e3o\" data-termo=\"Apela\u00e7\u00e3o\" data-significado=\"Recurso contra a senten\u00e7a dada pelo ju\u00edzo de primeiro grau, dirigido ao tribunal de segunda inst\u00e2ncia.\">apela\u00e7\u00e3o<\/span>. O relator concluiu que, afastada a possibilidade de <span class=\"\" data-match=\"agravo de instrumento\">agravo de instrumento<\/span>, deve ser seguido o disposto no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2015-2018\/2015\/lei\/l13105.htm#art1009%C2%A71\">artigo 1.009, par\u00e1grafo 1\u00ba, do CPC<\/a>.<\/p>\n<p><a href=\"https:\/\/processo.stj.jus.br\/processo\/julgamento\/eletronico\/documento\/mediado\/?documento_tipo=integra&amp;documento_sequencial=319126858&amp;registro_numero=202404368455&amp;peticao_numero=&amp;publicacao_data=20250616&amp;formato=PDF\">Leia o ac\u00f3rd\u00e3o no REsp 2.182.040<\/a>.<\/p>\n<p><strong>FONTE: Com informa\u00e7\u00e3o da Secretaria de Comunica\u00e7\u00e3o Social \u2013 STJ<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) concluiu que a decis\u00e3o que defere a realiza\u00e7\u00e3o de prova pericial n\u00e3o pode ser combatida por meio do recurso de agravo de instrumento. No curso de um incidente de desconsidera\u00e7\u00e3o da personalidade jur\u00eddica, o ju\u00edzo autorizou a produ\u00e7\u00e3o de per\u00edcia, o que resultou na interposi\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":1146,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[463,906,30],"coauthors":[870],"class_list":["post-1613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-agravo-de-instrumento","tag-cpc","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=1613"}],"version-history":[{"count":3,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1613\/revisions"}],"predecessor-version":[{"id":1616,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/1613\/revisions\/1616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/1146"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=1613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=1613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=1613"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=1613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}