{"id":284,"date":"2021-11-09T10:03:54","date_gmt":"2021-11-09T13:03:54","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=284"},"modified":"2021-11-09T10:03:54","modified_gmt":"2021-11-09T13:03:54","slug":"stj-prazo-prescricional-pode-ser-interrompido-uma-unica-vez-sob-a-egide-do-cc-2002","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-prazo-prescricional-pode-ser-interrompido-uma-unica-vez-sob-a-egide-do-cc-2002\/","title":{"rendered":"STJ: Prazo prescricional pode ser interrompido uma \u00fanica vez sob a \u00e9gide do CC\/2002"},"content":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) reafirmou que o <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/2002\/l10406.htm#art202\" target=\"_blank\" rel=\"noopener\"><strong>artigo 202 do C\u00f3digo Civil de 2002<\/strong><\/a> deve ser interpretado no sentido de que a interrup\u00e7\u00e3o da prescri\u00e7\u00e3o somente poder\u00e1 ocorrer uma vez para a mesma rela\u00e7\u00e3o jur\u00eddica, independentemente de seu fundamento.<\/p>\n<p>Com esse entendimento, o colegiado confirmou decis\u00e3o do Tribunal de Justi\u00e7a de S\u00e3o Paulo (TJSP) que negou provimento ao recurso de uma empresa, por considerar imposs\u00edvel reconhecer a interrup\u00e7\u00e3o do prazo prescricional em raz\u00e3o do ajuizamento de a\u00e7\u00e3o declarat\u00f3ria de inexist\u00eancia do d\u00e9bito pelo devedor, quando j\u00e1 houve anterior interrup\u00e7\u00e3o pelo protesto da duplicata.<\/p>\n<p>Segundo consta dos autos, o protesto da duplicata foi promovido em 17 de outubro de 2014, momento em que houve a interrup\u00e7\u00e3o do prazo prescricional, nos termos do inciso III do artigo 202 do C\u00f3digo Civil. Em 17 de dezembro daquele ano, houve o ajuizamento da a\u00e7\u00e3o declarat\u00f3ria de inexist\u00eancia de d\u00e9bito pelo devedor, hip\u00f3tese tamb\u00e9m apta a interromper a prescri\u00e7\u00e3o, conforme o mesmo dispositivo legal.<\/p>\n<p>Ao STJ, a empresa alegou que, na verdade, n\u00e3o houve uma nova interrup\u00e7\u00e3o do prazo prescricional, mas sim uma medida judicial que sustou liminarmente o direito do credor de executar o t\u00edtulo protestado, sob pena de incorrer em litispend\u00eancia.<\/p>\n<p>Dessa forma, o prazo prescricional s\u00f3 poderia come\u00e7ar a fluir em 19 de junho de 2017, momento em que houve o tr\u00e2nsito em julgado da demanda e o t\u00edtulo passou a possuir certeza, liquidez e exigibilidade.<\/p>\n<p><strong>Objetivo da prescri\u00e7\u00e3o \u00e9 dar estabilidade \u00e0s rela\u00e7\u00f5es jur\u00eddicas<\/strong><\/p>\n<p>Em seu voto, a relatora do recurso, ministra Nancy Andrighi, lembrou que o instituto da prescri\u00e7\u00e3o tem por objetivo conferir certeza \u00e0s rela\u00e7\u00f5es jur\u00eddicas, na busca de estabilidade, a fim de evitar uma perp\u00e9tua situa\u00e7\u00e3o de inseguran\u00e7a. Por\u00e9m, apesar disso, admite-se a interrup\u00e7\u00e3o do prazo prescricional quando o titular do direito manifesta, por uma das formas previstas em lei, a inten\u00e7\u00e3o de exerc\u00ea-la ou quando o devedor, de forma inequ\u00edvoca, reconhece aquele direito.<\/p>\n<p>Nancy Andrighi destacou ainda que o C\u00f3digo Civil de 2002 inovou ao dispor, de forma expressa, que a interrup\u00e7\u00e3o da prescri\u00e7\u00e3o s\u00f3 poder\u00e1 ocorrer uma vez. &#8220;Anteriormente, sob a \u00e9gide do antigo C\u00f3digo Civil, e ante o sil\u00eancio do diploma, discutia-se a possibilidade de a interrup\u00e7\u00e3o da prescri\u00e7\u00e3o ocorrer ilimitadamente&#8221;, lembrou.<\/p>\n<p>Segundo a magistrada, em rela\u00e7\u00e3o ao c\u00f3digo atual, h\u00e1 na doutrina alguma diverg\u00eancia sobre a interrup\u00e7\u00e3o: se ela ocorreria uma s\u00f3 vez, independentemente de seu fundamento, ou se poderia acontecer uma vez para cada uma das causas interruptivas previstas nos incisos do artigo 202.<\/p>\n<p>Apesar de alguns entendimentos doutrin\u00e1rios em sentido diverso, a ministra declarou que a previs\u00e3o expressa na atual reda\u00e7\u00e3o do c\u00f3digo n\u00e3o deixou d\u00favidas quanto \u00e0 impossibilidade de haver mais de uma interrup\u00e7\u00e3o da prescri\u00e7\u00e3o na mesma rela\u00e7\u00e3o jur\u00eddica, seja pelo mesmo fundamento ou por fundamentos diferentes \u2013 entendimento j\u00e1 aplicado pela Terceira Turma em outras situa\u00e7\u00f5es.<\/p>\n<p><strong>Protesto j\u00e1 havia interrompido o prazo prescricional<\/strong><\/p>\n<p>Especificamente no caso analisado, a relatora ressaltou que o ajuizamento posterior da a\u00e7\u00e3o declarat\u00f3ria de inexist\u00eancia de d\u00e9bito pelo devedor, embora possa ser causa interruptiva da prescri\u00e7\u00e3o, n\u00e3o leva a nova interrup\u00e7\u00e3o do prazo prescricional, pois ele j\u00e1 havia sido interrompido com o protesto da duplicata.<\/p>\n<p>&#8220;A prescri\u00e7\u00e3o de tr\u00eas anos (<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/2002\/l10406.htm#art206\" target=\"_blank\" rel=\"noopener\"><strong>artigo 206, par\u00e1grafo 3\u00ba, VIII, do CC<\/strong><\/a>) operou-se em 17 de outubro de 2017, sendo que a a\u00e7\u00e3o de execu\u00e7\u00e3o de t\u00edtulo executivo extrajudicial somente foi ajuizada pela recorrente em 17 de julho de 2018&#8243;, afirmou Nancy Andrighi.<\/p>\n<p><strong>PROCESSO RELACIONADO:<\/strong> <a href=\"https:\/\/processo.stj.jus.br\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=2080278&amp;num_registro=202002540755&amp;data=20210816&amp;peticao_numero=-1&amp;formato=PDF\" target=\"_blank\" rel=\"noopener\"><strong>REsp 1.924.436<\/strong><\/a>.<\/p>\n<p><strong>FONTE:<\/strong> STJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) reafirmou que o artigo 202 do C\u00f3digo Civil de 2002 deve ser interpretado no sentido de que a interrup\u00e7\u00e3o da prescri\u00e7\u00e3o somente poder\u00e1 ocorrer uma vez para a mesma rela\u00e7\u00e3o jur\u00eddica, independentemente de seu fundamento. Com esse entendimento, o colegiado confirmou decis\u00e3o do Tribunal de Justi\u00e7a [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[27,134,30],"coauthors":[],"class_list":["post-284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-direito-civil","tag-prescricao","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=284"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/284\/revisions"}],"predecessor-version":[{"id":285,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/284\/revisions\/285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/129"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=284"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}