{"id":297,"date":"2021-11-11T23:53:28","date_gmt":"2021-11-12T02:53:28","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=297"},"modified":"2021-11-11T23:58:59","modified_gmt":"2021-11-12T02:58:59","slug":"stj-mantida-condenacao-da-tv-globo-por-exposicao-de-inocente-em-programa-sobre-a-chacina-da-candelaria","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-mantida-condenacao-da-tv-globo-por-exposicao-de-inocente-em-programa-sobre-a-chacina-da-candelaria\/","title":{"rendered":"STJ: Mantida condena\u00e7\u00e3o da TV Globo por exposi\u00e7\u00e3o de inocente em programa sobre a Chacina da Candel\u00e1ria"},"content":{"rendered":"<p>A Quarta Turma do Superior Tribunal de Justi\u00e7a (STJ) ratificou decis\u00e3o de 2013 que manteve a condena\u00e7\u00e3o da TV Globo a indenizar em R$ 50 mil, por ofensa \u00e0 dignidade, um serralheiro que teve nome e imagem expostos em document\u00e1rio sobre a Chacina da Candel\u00e1ria apresentado no programa <em>Linha Direta \u2013 Justi\u00e7a<\/em>, em 2006.<\/p>\n<p>O epis\u00f3dio, que ficou conhecido mundialmente, ocorreu em 1993, pr\u00f3ximo \u00e0 Igreja da Candel\u00e1ria, no Rio de Janeiro, e resultou na morte de oito jovens moradores de rua. O serralheiro, que figurou entre os acusados pela trag\u00e9dia, foi absolvido no tribunal do j\u00fari em decis\u00e3o un\u00e2nime.<\/p>\n<p>No julgamento de 2013, o relator do processo, ministro Luis Felipe Salom\u00e3o, reconheceu ao serralheiro o direito ao esquecimento, diante do longo tempo transcorrido e da decis\u00e3o do conselho de senten\u00e7a.<\/p>\n<p>&#8220;Ressalvam-se do direito ao esquecimento os fatos genuinamente hist\u00f3ricos. Muito embora tenham as inst\u00e2ncias ordin\u00e1rias reconhecido que a reportagem se mostrou fidedigna com a realidade, a receptividade do homem m\u00e9dio brasileiro a notici\u00e1rios desse jaez \u00e9 apta a reacender a desconfian\u00e7a geral acerca da \u00edndole do autor, o qual, certamente, n\u00e3o teve refor\u00e7ada sua imagem de inocentado, mas sim a de indiciado&#8221;, afirmou Salom\u00e3o no voto proferido em 2013.<\/p>\n<p><strong>Direito ao esquecimento e direito de informar<\/strong><\/p>\n<p>A Globo interp\u00f4s recurso extraordin\u00e1rio, mas o processo ficou sobrestado, aguardando a decis\u00e3o do Supremo Tribunal Federal (STF) em um julgamento que tamb\u00e9m envolvia o direito ao esquecimento: o caso A\u00edda Curi (<a href=\"https:\/\/jurisprudencia.stf.jus.br\/pages\/search?classeNumeroIncidente=RE%201010606&amp;base=acordaos&amp;sinonimo=true&amp;plural=true&amp;page=1&amp;pageSize=10&amp;sort=_score&amp;sortBy=desc&amp;isAdvanced=true\"><strong>RE 1.010.606<\/strong><\/a>, Tema 786 da repercuss\u00e3o geral). Nele, o STF definiu que n\u00e3o h\u00e1 direito ao esquecimento capaz de impedir a divulga\u00e7\u00e3o de fatos antigos, mas ressalvou a possibilidade de puni\u00e7\u00e3o de abusos da liberdade de informa\u00e7\u00e3o.<\/p>\n<p>Em agosto, a Quarta Turma voltou a analisar o recurso sobre a Chacina da Candel\u00e1ria para verificar a necessidade de, eventualmente, ajustar sua posi\u00e7\u00e3o ao entendimento do STF, mas o rejulgamento do caso foi interrompido por pedido de vista do ministro Raul Ara\u00fajo.<\/p>\n<p>De acordo com a emissora, a situa\u00e7\u00e3o do processo se amoldaria \u00e0 tese do STF, segundo a qual &#8220;\u00e9 incompat\u00edvel com a Constitui\u00e7\u00e3o a ideia de um direito ao esquecimento, assim entendido como o poder de obstar, em raz\u00e3o da passagem do tempo, a divulga\u00e7\u00e3o de fatos ou dados ver\u00eddicos e licitamente obtidos e publicados em meios de comunica\u00e7\u00e3o social&#8221;.<\/p>\n<p><strong>Revolvimento dos fatos e ofensa \u00e0 dignidade do inocentado<\/strong><\/p>\n<p>O ministro Salom\u00e3o chamou aten\u00e7\u00e3o para a falta de contemporaneidade dos fatos noticiados no programa \u2013 o qual, segundo o autor da a\u00e7\u00e3o, trouxe \u00e0 tona dramas j\u00e1 administrados e resolvidos \u2013 e disse que a divulga\u00e7\u00e3o reacendeu um &#8220;ju\u00edzo social impiedoso&#8221; quanto ao seu car\u00e1ter, circunst\u00e2ncia que lhe causou profundo abalo emocional.<\/p>\n<p>&#8220;Permitir nova veicula\u00e7\u00e3o do fato, com a indica\u00e7\u00e3o precisa do nome e imagem do autor, significaria a permiss\u00e3o de uma segunda ofensa \u00e0 sua dignidade, s\u00f3 porque a primeira j\u00e1 ocorrera no passado, uma vez que, como bem reconheceu o ac\u00f3rd\u00e3o recorrido, al\u00e9m do crime em si, o inqu\u00e9rito policial consubstanciou uma reconhecida &#8216;vergonha&#8217; nacional \u00e0 parte&#8221;, declarou o relator.<\/p>\n<p>Ele destacou que o julgamento da Quarta Turma est\u00e1 em completa harmonia com a decis\u00e3o do STF, pois n\u00e3o guarda rela\u00e7\u00e3o com a primeira parte do Tema 786 \u2013 em que se fala do direito ao esquecimento \u2013, mas com a segunda parte, na qual ficou estabelecido que &#8220;eventuais excessos ou abusos no exerc\u00edcio da liberdade de express\u00e3o e de informa\u00e7\u00e3o devem ser analisados caso a caso, a partir dos par\u00e2metros constitucionais \u2013 especialmente os relativos \u00e0 prote\u00e7\u00e3o da honra, da imagem, da privacidade e da personalidade em geral \u2013 e das expressas e espec\u00edficas previs\u00f5es legais nos \u00e2mbitos penal e c\u00edvel&#8221;.<\/p>\n<p>&#8220;Constatou-se exatamente a situa\u00e7\u00e3o abusiva referida pelo Supremo, situa\u00e7\u00e3o para a qual aquele tribunal determinou: em sendo constatado o excesso na divulga\u00e7\u00e3o de fatos ou dados ver\u00eddicos e licitamente obtidos e publicados em meios de comunica\u00e7\u00e3o social anal\u00f3gicos ou digitais, proceda-se o julgador competente ao estancamento da viola\u00e7\u00e3o, a partir das leg\u00edtimas formas previstas pelo ordenamento&#8221;.<\/p>\n<p><strong>Situa\u00e7\u00f5es definidas no Tema 786\/STF<\/strong><\/p>\n<p>Para o ministro, s\u00e3o duas situa\u00e7\u00f5es diferentes definidas no Tema 786: em uma, h\u00e1 apenas o descontentamento com a informa\u00e7\u00e3o que n\u00e3o \u00e9 conveniente \u00e0 pessoa, e nesse caso o direito \u00e0 informa\u00e7\u00e3o e a liberdade de imprensa preponderam em rela\u00e7\u00e3o \u00e0 intimidade, \u00e0 imagem e \u00e0 vida privada; na outra, h\u00e1 o exerc\u00edcio irrespons\u00e1vel e abusivo dos direitos de informa\u00e7\u00e3o, de express\u00e3o e de liberdade de imprensa, diante do qual o controle judicial dever\u00e1 ser imperativo, sempre considerando as peculiaridades de cada caso.<\/p>\n<p>&#8220;Os pressupostos que alicer\u00e7aram o entendimento do STF s\u00e3o absolutamente coincidentes com aqueles nos quais se estruturou a decis\u00e3o tomada no recurso especial aqui decidido, justificando-se a confirma\u00e7\u00e3o do julgado proferido por este colegiado&#8221;, concluiu Salom\u00e3o.<\/p>\n<p><strong>PROCESSO RELACIONADO:<\/strong> <span id=\"pstj_elContItensProcessosRelacionados\" class=\"obj_textos_rel_processos\"><a class=\"\" href=\"https:\/\/ww2.stj.jus.br\/processo\/pesquisa\/?aplicacao=processos.ea&amp;tipoPesquisa=tipoPesquisaGenerica&amp;termo=REsp 1334097\" target=\"janela_processos\" rel=\"noopener\">REsp 1334097<\/a><\/span><\/p>\n<p><strong>FONTE:<\/strong> STJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Quarta Turma do Superior Tribunal de Justi\u00e7a (STJ) ratificou decis\u00e3o de 2013 que manteve a condena\u00e7\u00e3o da TV Globo a indenizar em R$ 50 mil, por ofensa \u00e0 dignidade, um serralheiro que teve nome e imagem expostos em document\u00e1rio sobre a Chacina da Candel\u00e1ria apresentado no programa Linha Direta \u2013 Justi\u00e7a, em 2006. O [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":301,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[140,139,83,30],"coauthors":[],"class_list":["post-297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-dignidade","tag-direito-ao-esquecimento","tag-indenizacao","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=297"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/297\/revisions"}],"predecessor-version":[{"id":299,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/297\/revisions\/299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/301"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=297"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}