{"id":440,"date":"2022-03-21T15:52:21","date_gmt":"2022-03-21T18:52:21","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=440"},"modified":"2022-03-21T15:52:21","modified_gmt":"2022-03-21T18:52:21","slug":"stf-custas-judiciais-do-stf-poderao-ser-recolhidas-com-pix-ou-cartao-de-credito-a-partir-de-abril","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stf-custas-judiciais-do-stf-poderao-ser-recolhidas-com-pix-ou-cartao-de-credito-a-partir-de-abril\/","title":{"rendered":"STF: Custas judiciais do STF poder\u00e3o ser recolhidas com Pix ou cart\u00e3o de cr\u00e9dito a partir de abril"},"content":{"rendered":"<p>O Portal do Supremo Tribunal Federal passa a oferecer, a partir de abril, uma nova modalidade de recolhimento das custas judiciais, por meio da plataforma digital do PagTesouro, da Secretaria do Tesouro Nacional da Secretaria Especial de Fazenda. Com a novidade, o jurisdicionado tem a op\u00e7\u00e3o de fazer o pagamento por Pix e por cart\u00e3o de cr\u00e9dito, que se somam \u00e0 modalidade existente da GRU compensa\u00e7\u00e3o.<\/p>\n<p>O servi\u00e7o permite, ainda, a emiss\u00e3o do comprovante de pagamento, que ser\u00e1 disponibilizado no Portal do STF e constitui documento h\u00e1bil para fins de comprova\u00e7\u00e3o do recolhimento das custas judiciais.<\/p>\n<p>Essa e outras iniciativas do STF foram priorizadas para melhorar a experi\u00eancia do jurisdicionado, expandindo e facilitando o acesso aos servi\u00e7os oferecidos \u00e0 sociedade.<\/p>\n<p>O PagTesouro foi institu\u00eddo pelo Decreto 10.494\/2020 como plataforma digital para pagamento e recolhimento de valores \u00e0 Conta \u00danica do Tesouro Nacional. No \u00e2mbito do STF, a nova forma de pagamento est\u00e1 prevista na <a href=\"http:\/\/www.stf.jus.br\/arquivo\/norma\/resolucao766-2022.pdf\">Resolu\u00e7\u00e3o 766<\/a>, de 11\/3\/2022, que estabelece prazo de 30 dias para sua entrada em vigor. At\u00e9 l\u00e1, o recolhimento continuar\u00e1 a ser feito exclusivamente via GRU.<\/p>\n<p>O secret\u00e1rio-geral da Presid\u00eancia do STF, Pedro Felipe de Oliveira Santos, ressalta a import\u00e2ncia da oferta das novas modalidades de pagamento, \u201ccomo forma de amplificar o acesso \u00e0 jurisdi\u00e7\u00e3o utilizando-se dos pr\u00e9stimos da inova\u00e7\u00e3o tecnol\u00f3gica\u201d.<\/p>\n<p><strong>FONTE:<\/strong> Com informa\u00e7\u00f5es da assessoria de comunica\u00e7\u00e3o social do STF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Portal do Supremo Tribunal Federal passa a oferecer, a partir de abril, uma nova modalidade de recolhimento das custas judiciais, por meio da plataforma digital do PagTesouro, da Secretaria do Tesouro Nacional da Secretaria Especial de Fazenda. Com a novidade, o jurisdicionado tem a op\u00e7\u00e3o de fazer o pagamento por Pix e por cart\u00e3o [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[230,231,6],"coauthors":[],"class_list":["post-440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-custas","tag-pix","tag-stf"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=440"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/440\/revisions"}],"predecessor-version":[{"id":442,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/440\/revisions\/442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/441"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=440"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}