{"id":473,"date":"2022-04-07T15:10:00","date_gmt":"2022-04-07T18:10:00","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=473"},"modified":"2022-04-07T15:10:00","modified_gmt":"2022-04-07T18:10:00","slug":"stj-lei-maria-da-penha-e-aplicavel-a-violencia-contra-mulher-trans","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-lei-maria-da-penha-e-aplicavel-a-violencia-contra-mulher-trans\/","title":{"rendered":"STJ: Lei Maria da Penha \u00e9 aplic\u00e1vel \u00e0 viol\u00eancia contra mulher trans"},"content":{"rendered":"<p>Por unanimidade, a Sexta Turma do Superior Tribunal de Justi\u00e7a (STJ) estabeleceu que a Lei Maria da Penha se aplica aos casos de viol\u00eancia dom\u00e9stica ou familiar contra mulheres transexuais. Considerando que, para efeito de incid\u00eancia da lei, mulher trans \u00e9 mulher tamb\u00e9m, o colegiado deu <span class=\"termo-glossario\" data-match=\"provimento\" data-termo=\"Provimento\" data-significado=\"Pode ser o ato administrativo do qual \u00e9 preenchido cargo p\u00fablico. Em recursos, a express\u00e3o dar provimento \u00e9 utilizada quando h\u00e1 \u00eaxito no recurso da parte.\"><span class=\"termo\">provimento<\/span><\/span><\/p>\n<p>a recurso do Minist\u00e9rio P\u00fablico de S\u00e3o Paulo e determinou a aplica\u00e7\u00e3o das medidas protetivas requeridas por uma transexual, nos termos do <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2004-2006\/2006\/lei\/l11340.htm#art22\" target=\"_blank\" rel=\"noopener\"><strong>artigo 22 da Lei 11.340\/2006<\/strong><\/a>, ap\u00f3s ela sofrer agress\u00f5es do seu pai na resid\u00eancia da fam\u00edlia.<\/p>\n<p>&#8220;Este julgamento versa sobre a vulnerabilidade de uma categoria de seres humanos, que n\u00e3o pode ser resumida \u00e0 objetividade de uma ci\u00eancia exata. As exist\u00eancias e as rela\u00e7\u00f5es humanas s\u00e3o complexas, e o direito n\u00e3o se deve alicer\u00e7ar em discursos rasos, simplistas e reducionistas, especialmente nestes tempos de naturaliza\u00e7\u00e3o de falas de \u00f3dio contra minorias&#8221;, afirmou o relator, ministro Rogerio Schietti Cruz.<\/p>\n<p>O ju\u00edzo de primeiro grau e o Tribunal de Justi\u00e7a de S\u00e3o Paulo (TJSP) negaram as medidas protetivas, entendendo que a prote\u00e7\u00e3o da Maria da Penha seria limitada \u00e0 condi\u00e7\u00e3o de mulher biol\u00f3gica. Ao STJ, o Minist\u00e9rio P\u00fablico argumentou que n\u00e3o se trata de fazer analogia, mas de aplicar simplesmente o texto da lei, cujo <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2004-2006\/2006\/lei\/l11340.htm#art5\" target=\"_blank\" rel=\"noopener\"><strong>artigo 5\u00ba<\/strong><\/a>, ao definir seu \u00e2mbito de incid\u00eancia, refere-se \u00e0 viol\u00eancia &#8220;baseada no g\u00eanero&#8221;, e n\u00e3o no sexo biol\u00f3gico.<\/p>\n<p><strong>Viol\u00eancia contra a mulher nasce da rela\u00e7\u00e3o de domina\u00e7\u00e3o<\/strong><\/p>\n<p>Em seu voto, o relator abordou os conceitos de sexo, g\u00eanero e identidade de g\u00eanero, com base na doutrina especializada e na <a href=\"https:\/\/atos.cnj.jus.br\/files\/original18063720220217620e8ead8fae2.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Recomenda\u00e7\u00e3o 128 do Conselho Nacional de Justi\u00e7a (CNJ)<\/strong><\/a>, que adotou protocolo para julgamentos com perspectiva de g\u00eanero. Segundo o magistrado, &#8220;g\u00eanero \u00e9 quest\u00e3o cultural, social, e significa intera\u00e7\u00f5es entre homens e mulheres&#8221;, enquanto sexo se refere \u00e0s caracter\u00edsticas biol\u00f3gicas dos aparelhos reprodutores feminino e masculino, de modo que, para ele, o conceito de sexo &#8220;n\u00e3o define a identidade de g\u00eanero&#8221;.<\/p>\n<p>Para o ministro, a Lei Maria da Penha n\u00e3o faz considera\u00e7\u00f5es sobre a motiva\u00e7\u00e3o do agressor, mas apenas exige, para sua aplica\u00e7\u00e3o, que a v\u00edtima seja mulher e que a viol\u00eancia seja cometida em ambiente dom\u00e9stico e familiar ou no contexto de rela\u00e7\u00e3o de intimidade ou afeto entre agressor e agredida.<\/p>\n<p>Schietti ressaltou entendimentos doutrin\u00e1rios segundo os quais o elemento diferenciador da abrang\u00eancia da lei \u00e9 o g\u00eanero feminino, sendo que nem sempre o sexo biol\u00f3gico e a identidade subjetiva coincidem. &#8220;O verdadeiro objetivo da Lei Maria da Penha seria punir, prevenir e erradicar a viol\u00eancia dom\u00e9stica e familiar contra a mulher em virtude do g\u00eanero, e n\u00e3o por raz\u00e3o do sexo&#8221;, declarou o magistrado.<\/p>\n<p>Ele mencionou que o Brasil responde, sozinho, por 38,2% dos homic\u00eddios contra pessoas trans no mundo, e apontou a necessidade de &#8220;desconstru\u00e7\u00e3o do cen\u00e1rio da heteronormatividade&#8221;, permitindo o acolhimento e o tratamento igualit\u00e1rio de pessoas com diferen\u00e7as.<\/p>\n<p>Quanto \u00e0 aplica\u00e7\u00e3o da Maria da Penha, o ministro lembrou que a viol\u00eancia de g\u00eanero &#8220;\u00e9 resultante da organiza\u00e7\u00e3o social de g\u00eanero, a qual atribui posi\u00e7\u00e3o de superioridade ao homem. A viol\u00eancia contra a mulher nasce da rela\u00e7\u00e3o de domina\u00e7\u00e3o\/subordina\u00e7\u00e3o, de modo que ela sofre as agress\u00f5es pelo fato de ser mulher&#8221;.<\/p>\n<p><strong>Viol\u00eancia em ambiente dom\u00e9stico contra mulheres<\/strong><\/p>\n<p>No caso em an\u00e1lise, o ministro verificou que a agress\u00e3o foi praticada n\u00e3o apenas em ambiente dom\u00e9stico, mas tamb\u00e9m familiar e afetivo, pelo pai contra a filha \u2013 o que elimina qualquer d\u00favida quanto \u00e0 incid\u00eancia do subsistema legal da Maria da Penha, inclusive no que diz respeito \u00e0 compet\u00eancia da vara judicial especializada para julgar a <span class=\"termo-glossario\" data-match=\"a\u00e7\u00e3o penal\" data-termo=\"A\u00e7\u00e3o Penal\" data-significado=\"A a\u00e7\u00e3o penal \u00e9 o direito ou o poder-dever de provocar o Poder Judici\u00e1rio para que decida o conflito nascido com a pr\u00e1tica de conduta definida em lei como crime para aplica\u00e7\u00e3o do direito penal objetivo a caso concreto.\"><span class=\"termo\">a\u00e7\u00e3o penal<\/span><\/span>.<\/p>\n<p>&#8220;A Lei Maria da Penha nada mais objetiva do que proteger v\u00edtimas em situa\u00e7\u00e3o como a da ofendida destes autos. Os abusos por ela sofridos aconteceram no ambiente familiar e dom\u00e9stico e decorreram da distor\u00e7\u00e3o sobre a rela\u00e7\u00e3o oriunda do p\u00e1trio poder, em que se pressup\u00f5e intimidade e afeto, al\u00e9m do fator essencial de ela ser mulher&#8221;, concluiu.<\/p>\n<p>Schietti destacou o voto divergente da desembargadora Rachid Vaz de Almeida no TJSP, os julgados de tribunais locais que aplicaram a Maria da Penha para mulheres trans, os entendimentos do Supremo Tribunal Federal (STF) e do pr\u00f3prio STJ sobre quest\u00f5es de g\u00eanero e o parecer do Minist\u00e9rio P\u00fablico Federal no caso em julgamento, favor\u00e1vel ao <span class=\"termo-intermed\" data-match=\"provimento\">provimento<\/span> do recurso \u2013 que ele considerou &#8220;brilhante&#8221;.<\/p>\n<p><em>O n\u00famero deste processo n\u00e3o \u00e9 divulgado em raz\u00e3o de segredo judicial.<\/em><\/p>\n<p><strong>FONTE:<\/strong> Com informa\u00e7\u00f5es da assessoria de comunica\u00e7\u00e3o social do STJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por unanimidade, a Sexta Turma do Superior Tribunal de Justi\u00e7a (STJ) estabeleceu que a Lei Maria da Penha se aplica aos casos de viol\u00eancia dom\u00e9stica ou familiar contra mulheres transexuais. Considerando que, para efeito de incid\u00eancia da lei, mulher trans \u00e9 mulher tamb\u00e9m, o colegiado deu provimento a recurso do Minist\u00e9rio P\u00fablico de S\u00e3o Paulo [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[246,30,247,248],"coauthors":[],"class_list":["post-473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-lei-maria-da-penha","tag-stj","tag-transgenero","tag-violencia-de-genero"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/473\/revisions"}],"predecessor-version":[{"id":475,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/473\/revisions\/475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/474"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=473"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}