{"id":493,"date":"2022-04-26T11:46:23","date_gmt":"2022-04-26T14:46:23","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=493"},"modified":"2022-04-26T11:46:23","modified_gmt":"2022-04-26T14:46:23","slug":"stj-pacote-anticrime-nao-retirou-o-carater-hediondo-do-trafico-de-drogas","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-pacote-anticrime-nao-retirou-o-carater-hediondo-do-trafico-de-drogas\/","title":{"rendered":"STJ: Pacote Anticrime n\u00e3o retirou o car\u00e1ter hediondo do tr\u00e1fico de drogas"},"content":{"rendered":"<p>A Quinta Turma do Superior Tribunal de Justi\u00e7a (STJ) estabeleceu que as altera\u00e7\u00f5es promovidas pela <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2019-2022\/2019\/lei\/L13964.htm\" target=\"_blank\" rel=\"noopener\"><strong>Lei 13.964\/2019<\/strong><\/a> \u2013 conhecida como Pacote Anticrime \u2013 na Lei 8.072\/1990 n\u00e3o retiraram a equipara\u00e7\u00e3o do delito de tr\u00e1fico de entorpecentes a crime hediondo. O colegiado destacou que a classifica\u00e7\u00e3o da narcotrafic\u00e2ncia como infra\u00e7\u00e3o penal equiparada a hedionda est\u00e1 prevista na pr\u00f3pria Constitui\u00e7\u00e3o (<a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm#art5XLIII\" target=\"_blank\" rel=\"noopener\"><strong>artigo 5\u00ba, inciso XLIII<\/strong><\/a>).<\/p>\n<p>O entendimento foi fixado pela turma ao rejeitar <span class=\"termo-glossario\" data-match=\"habeas corpus\" data-termo=\"Habeas Corpus\" data-significado=\"A\u00e7\u00e3o, prevista constitucionalmente, cab\u00edvel sempre que algu\u00e9m sofrer ou se achar amea\u00e7ado de sofrer viol\u00eancia ou coa\u00e7\u00e3o em sua liberdade de locomo\u00e7\u00e3o, por ilegalidade ou abuso de poder.\"><span class=\"termo\">habeas corpus<\/span><\/span><\/p>\n<p>que buscava o reconhecimento de que o tr\u00e1fico de drogas teria perdido a sua caracteriza\u00e7\u00e3o como crime equiparado a hediondo ap\u00f3s o in\u00edcio da vig\u00eancia do Pacote Anticrime, que revogou o artigo 2\u00ba, par\u00e1grafo 2\u00ba, da Lei 8.072\/1990. O dispositivo trazia par\u00e2metros para a progress\u00e3o de regime no caso de crimes hediondos e equiparados \u2013 a pr\u00e1tica da tortura, o tr\u00e1fico de drogas e o terrorismo.<\/p>\n<p>Como consequ\u00eancia da revoga\u00e7\u00e3o do dispositivo, a defesa pedia a aplica\u00e7\u00e3o, ao delito de tr\u00e1fico, das fra\u00e7\u00f5es de progress\u00e3o de regime previstas na Lei de Execu\u00e7\u00e3o Penal (LEP) para os crimes comuns.<\/p>\n<p><strong>Constitui\u00e7\u00e3o prev\u00ea tratamento mais severo para o tr\u00e1fico de drogas<\/strong><\/p>\n<p>O relator do <span class=\"termo-intermed\" data-match=\"habeas corpus\">habeas corpus<\/span>, ministro Reynaldo Soares da Fonseca, explicou que, nos termos do artigo 5\u00ba, inciso XLIII, da Constitui\u00e7\u00e3o, a lei considerar\u00e1 inafian\u00e7\u00e1veis e insuscet\u00edveis de gra\u00e7a ou anistia a pr\u00e1tica de tortura, o tr\u00e1fico il\u00edcito de entorpecentes, o terrorismo e os definidos como crimes hediondos.<\/p>\n<p>&#8220;O pr\u00f3prio constituinte assegurou que o tr\u00e1fico de drogas, a tortura e o terrorismo s\u00e3o merecedores de tratamento penal mais severo&#8221;, complementou.<\/p>\n<p>De acordo com o ministro, o fato de o Pacote Anticrime ter expressamente consignado, no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l7210.htm#art112%C2%A75\" target=\"_blank\" rel=\"noopener\"><strong>artigo 112, par\u00e1grafo 5\u00ba, da LEP<\/strong><\/a>, que n\u00e3o se considera hediondo ou equiparado a ele o tr\u00e1fico de drogas descrito no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2004-2006\/2006\/lei\/l11343.htm#art33%C2%A74\" target=\"_blank\" rel=\"noopener\"><strong>artigo 33, par\u00e1grafo 4\u00ba, da Lei 11.343\/2006<\/strong><\/a> apenas consagrou o tratamento diferenciado que j\u00e1 era atribu\u00eddo pela jurisprud\u00eancia ao tr\u00e1fico privilegiado.<\/p>\n<p>&#8220;Isso, no entanto, n\u00e3o autoriza deduzir que a mesma descaracteriza\u00e7\u00e3o como delito equiparado a hediondo tenha sido estendida ao crime do <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2004-2006\/2006\/lei\/l11343.htm#art33\" target=\"_blank\" rel=\"noopener\"><strong>artigo 33, <\/strong><strong><em>caput<\/em><\/strong><strong> e par\u00e1grafo 1\u00ba, da Lei de Drogas<\/strong><\/a>&#8220;, afirmou o relator.<\/p>\n<p><strong>Repetitivo de 2021 tratou tr\u00e1fico no contexto dos crimes equiparados a hediondo<\/strong><\/p>\n<p>Reynaldo Soares da Fonseca tamb\u00e9m lembrou que a Terceira Se\u00e7\u00e3o, em 2021 \u2013 ap\u00f3s o Pacote Anticrime, portanto \u2013, no julgamento do <a href=\"http:\/\/www.stj.jus.br\/repetitivos\/temas_repetitivos\/pesquisa.jsp?novaConsulta=true&amp;tipo_pesquisa=T&amp;cod_tema_inicial=1084&amp;cod_tema_final=1084\"><strong>Tema Repetitivo 1.084<\/strong><\/a>, reconheceu a possibilidade de aplica\u00e7\u00e3o retroativa do artigo 112, inciso V, da LEP a condenados por crimes hediondos ou equiparados que fossem reincidentes gen\u00e9ricos \u2013 e o caso concreto dizia respeito especificamente a condenado por tr\u00e1fico de drogas.<\/p>\n<p>&#8220;Patente, assim, que a jurisprud\u00eancia desta corte \u00e9 assente no sentido de que as altera\u00e7\u00f5es trazidas pela Lei 13.964\/2019 em nada influenciaram na qualifica\u00e7\u00e3o do crime de tr\u00e1fico de drogas como delito equiparado a hediondo&#8221;, concluiu o ministro.<\/p>\n<p><strong>PROCESSO RELACIONADO:<\/strong> <a href=\"https:\/\/processo.stj.jus.br\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=2161984&amp;num_registro=202200728185&amp;data=20220425&amp;peticao_numero=202200267183&amp;formato=PDF\"><strong>HC 729.332<\/strong><\/a>.<\/p>\n<p><strong>FONTE:<\/strong> Com informa\u00e7\u00f5es da Assessoria de Comunica\u00e7\u00e3o Social do STJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Quinta Turma do Superior Tribunal de Justi\u00e7a (STJ) estabeleceu que as altera\u00e7\u00f5es promovidas pela Lei 13.964\/2019 \u2013 conhecida como Pacote Anticrime \u2013 na Lei 8.072\/1990 n\u00e3o retiraram a equipara\u00e7\u00e3o do delito de tr\u00e1fico de entorpecentes a crime hediondo. O colegiado destacou que a classifica\u00e7\u00e3o da narcotrafic\u00e2ncia como infra\u00e7\u00e3o penal equiparada a hedionda est\u00e1 prevista [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[258,30,53],"coauthors":[],"class_list":["post-493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-crimes-hediondos-e-assemelhados","tag-stj","tag-trafico-de-drogas"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=493"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/493\/revisions"}],"predecessor-version":[{"id":495,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/493\/revisions\/495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/494"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=493"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}