{"id":514,"date":"2022-05-06T10:45:03","date_gmt":"2022-05-06T13:45:03","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=514"},"modified":"2022-05-06T10:45:03","modified_gmt":"2022-05-06T13:45:03","slug":"tst-vendedora-submetida-a-pressao-e-clima-de-psicoterror-sera-indenizada-por-industria","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/tst-vendedora-submetida-a-pressao-e-clima-de-psicoterror-sera-indenizada-por-industria\/","title":{"rendered":"TST: Vendedora submetida a press\u00e3o e clima de \u201cpsicoterror\u201d ser\u00e1 indenizada por ind\u00fastria"},"content":{"rendered":"<p>A S\u00e9tima Turma do Tribunal Superior do Trabalho rejeitou o exame do recurso de revista da Plas\u00fatil Ind\u00fastria e Com\u00e9rcio de Pl\u00e1sticos Ltda. contra decis\u00e3o que a condenara a indenizar uma vendedora, em raz\u00e3o de ass\u00e9dio moral. Para o colegiado, as provas mencionadas na decis\u00e3o evidenciaram que a trabalhadora foi v\u00edtima de press\u00e3o desmedida durante toda a rela\u00e7\u00e3o de emprego.<\/p>\n<p><strong>Entenda o caso<\/strong><\/p>\n<p>Na reclama\u00e7\u00e3o trabalhista, a vendedora, que atuava na Regi\u00e3o Metropolitana de Belo Horizonte (MG), afirmou etr sido v\u00edtima de conduta abusiva do gerente regional, \u201cque demonstrava, de forma muito clara, a inten\u00e7\u00e3o de provocar um pedido de demiss\u00e3o\u201d. Segundo ela, as investidas abrangiam a redu\u00e7\u00e3o de sua \u00e1rea de trabalho, a retirada de clientes sem justificativa, o aumento desproporcional de cotas, a desqualifica\u00e7\u00e3o em reuni\u00f5es ou por mensagens e o boicote a negocia\u00e7\u00f5es conduzidas por ela com clientes.<\/p>\n<p><strong>\u201cPsicoterror\u201d<\/strong><\/p>\n<p>O Tribunal Regional do Trabalho da 3\u00aa Regi\u00e3o (MG) condenou a empresa por ass\u00e9dio moral, por considerar que, durante toda a rela\u00e7\u00e3o de trabalho, a empregada estivera submetida a uma press\u00e3o extraordin\u00e1ria, se comparada aos colegas, num quadro de \u201cpsicoterror\u201d. Na decis\u00e3o, o TRT menciona expressamente as provas testemunhais que confirmaram a press\u00e3o. Desse modo, a Plas\u00fatil foi condenada ao pagamento de R$ 15 mil, a t\u00edtulo de indeniza\u00e7\u00e3o por dano moral.<\/p>\n<p><strong>Mat\u00e9ria de fato<\/strong><\/p>\n<p>O relator do recurso de revista da ind\u00fastria, ministro Evandro Valad\u00e3o, assinalou que a empresa n\u00e3o pretendia uma nova aprecia\u00e7\u00e3o jur\u00eddica dos fatos registrados na decis\u00e3o do TRT, mas uma nova valora\u00e7\u00e3o dos elementos constantes do processo. \u201cO TRT \u00e9 soberano na an\u00e1lise dos fatos e das provas, e a decis\u00e3o do Tribunal mineiro observou circunst\u00e2ncias que levaram \u00e0 condena\u00e7\u00e3o da empresa, atestando que a empregada era v\u00edtima de desmedida press\u00e3o\u201d, afirmou.<\/p>\n<p>No seu voto, acolhido \u00e0 unanimidade pela Turma, o relator registrou que n\u00e3o h\u00e1, na decis\u00e3o do TRT, nenhuma d\u00favida sobre a longa dura\u00e7\u00e3o das condi\u00e7\u00f5es caracterizadoras do ass\u00e9dio moral, que eram comuns e reiteradas. Para alcan\u00e7ar conclus\u00e3o em sentido contr\u00e1rio, seria necess\u00e1rio rever os fatos e as provas conduta vedada em recurso de revista pela S\u00famula 126 do TST.<\/p>\n<p>A decis\u00e3o foi un\u00e2nime.<\/p>\n<p><strong>PROCESSO RELACIONADO:<\/strong> <a href=\"https:\/\/consultaprocessual.tst.jus.br\/consultaProcessual\/consultaTstNumUnica.do?consulta=Consultar&amp;conscsjt=&amp;numeroTst=10373&amp;digitoTst=96&amp;anoTst=2016&amp;orgaoTst=5&amp;tribunalTst=03&amp;varaTst=0139&amp;submit=Consultar\" target=\"_blank\" rel=\"noopener\" data-senna-off=\"true\">RR-10373-96.2016.5.03.0139<\/a><\/p>\n<p><strong>FONTE:<\/strong> Com informa\u00e7\u00f5es da Assessoria de Comunica\u00e7\u00e3o Social do TST<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A S\u00e9tima Turma do Tribunal Superior do Trabalho rejeitou o exame do recurso de revista da Plas\u00fatil Ind\u00fastria e Com\u00e9rcio de Pl\u00e1sticos Ltda. contra decis\u00e3o que a condenara a indenizar uma vendedora, em raz\u00e3o de ass\u00e9dio moral. Para o colegiado, as provas mencionadas na decis\u00e3o evidenciaram que a trabalhadora foi v\u00edtima de press\u00e3o desmedida durante [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":515,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[83,271,64],"coauthors":[],"class_list":["post-514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-indenizacao","tag-psicoterror","tag-tst"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=514"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/514\/revisions"}],"predecessor-version":[{"id":516,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/514\/revisions\/516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/515"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=514"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}