{"id":536,"date":"2022-05-26T20:59:25","date_gmt":"2022-05-26T23:59:25","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=536"},"modified":"2022-05-26T20:59:25","modified_gmt":"2022-05-26T23:59:25","slug":"stj-autorizacao-para-escuta-telefonica-depende-da-instauracao-de-inquerito-policial","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-autorizacao-para-escuta-telefonica-depende-da-instauracao-de-inquerito-policial\/","title":{"rendered":"STJ: Autoriza\u00e7\u00e3o para escuta telef\u00f4nica depende da instaura\u00e7\u00e3o de inqu\u00e9rito policial"},"content":{"rendered":"<p><strong>Por: Cl\u00e1udio Pereira Ramos<\/strong><\/p>\n<p>N\u00e3o h\u00e1 um t\u00edtulo ou par\u00e1grafo introdut\u00f3rio que situe o leitor sobre o que esperar, portanto n\u00e3o sabemos de que se trata e ca\u00edmos direto no texto, sobre uma senten\u00e7a n\u00e3o conhecida.<\/p>\n<p>Os recorrentes, que s\u00e3o policiais, entraram com recurso contra o ac\u00f3rd\u00e3o do Tribunal de Justi\u00e7a do Rio de Janeiro (TJRJ). A decis\u00e3o do HC n. 0054065-08.2021.8.19.0000, que denegou a ordem pleiteada, reconheceu que houve deferimento pelo juiz para que haja intercepta\u00e7\u00e3o telef\u00f4nica dos policiais citados anteriormente, bem como da autoridade policial da delegacia na qual estavam lotados, sendo que essa intercepta\u00e7\u00e3o abrangeu todos os telefones fixos e m\u00f3veis de tais pessoas, al\u00e9m dos os telefones da delegacia de pol\u00edcia onde encontram-se lotados os recorrentes.<\/p>\n<p>Os apelantes argumentam que tal decis\u00e3o teve como base dela\u00e7\u00f5es an\u00f4nimas, n\u00e3o havendo provas concretas, inexistindo averigua\u00e7\u00f5es pr\u00e9vias sobre a proced\u00eancia das den\u00fancias, o que \u00e9 inadmiss\u00edvel<span style=\"text-decoration: line-through\">.<\/span> Sendo assim, os apelantes pleitearam a nulidade da decis\u00e3o.<\/p>\n<p>Pelas den\u00fancias an\u00f4nimas recebidas pelo Minist\u00e9rio P\u00fablico, no que foi informado que um cidad\u00e3o estava sendo extorquido por policiais civis, sendo todos lotados em uma mesma Delegacia de Pol\u00edcia. Foi relatado na den\u00fancia que, em raz\u00e3o de cumprimento de mandado de busca e apreens\u00e3o, tais policiais, por meio de grave amea\u00e7a, constrangeram a v\u00edtima a entregar lhes a exorbitante quantia de R$ 200.000,00 (duzentos mil reais), ainda com o objetivo de evitar a pris\u00e3o em flagrante, visto que com a v\u00edtima teriam sido encontradas armas de fogo, diversos carros de proced\u00eancia duvidosa, v\u00e1rios cheques, etc. Segundo a den\u00fancia, tal quantia foi paga pela v\u00edtima e os referidos policiais deixaram de fazer os registros pertinentes aos fatos descobertos por ocasi\u00e3o do cumprimento do mandado de busca e apreens\u00e3o.<\/p>\n<p>Outra den\u00fancia recebida<span style=\"text-decoration: line-through\">,<\/span> relata que a mesma pessoa foi novamente extorquida durante o que seria uma pris\u00e3o em flagrante no contexto de saque de parte de uma carga perec\u00edvel e que a referida pessoa teria sido liberada ou em virtude do pagamento de quantia em dinheiro que lhe foi extorquida ou exigida, ou a pedido de um Prefeito Municipal.<\/p>\n<p>Em raz\u00e3o das sucessivas extors\u00f5es, h\u00e1 not\u00edcia, decorrente tamb\u00e9m da den\u00fancia an\u00f4nima, de que a v\u00edtima mudou de endere\u00e7o, estando vivendo em outro Estado da Federa\u00e7\u00e3o por medo dos policiais, o que de fato vem refor\u00e7ar a ocorr\u00eancia dos crimes. Al\u00e9m dessas den\u00fancias, a Promotoria de Justi\u00e7a vem recebendo outras den\u00fancias apontando situa\u00e7\u00f5es semelhantes como a acima narrada.<\/p>\n<p>Assim, com base em tais den\u00fancias, foi tomada a decis\u00e3o sobre a qual os policiais citados inicialmente entraram com recurso. Ap\u00f3s an\u00e1lise dos fatos, foi averiguado pelo Ministro-relator do Superior Tribunal de Justi\u00e7a, que usar a den\u00fancia para arregimentar mecanismos cautelares excepcionais de colheita de elementos de informa\u00e7\u00e3o e de comprova\u00e7\u00e3o de fatos supostamente delituosos, somente seria poss\u00edvel com a abertura do inqu\u00e9rito policial, o que n\u00e3o ocorreu.<\/p>\n<p>Sendo assim, o ministro citado deu provimento ao recurso interposto pelos policiais, reconhecendo a nulidade das intercepta\u00e7\u00f5es telef\u00f4nicas decretadas em fun\u00e7\u00e3o da decis\u00e3o proferida, devendo o Juiz natural identificar as provas delas derivadas, que dever\u00e3o ser invalidadas, aplicando-se o princ\u00edpio dos frutos da \u00e1rvore envenenada.<\/p>\n<p><strong>PROCESSO RELACIONADO:<\/strong> RECURSO EM HABEAS CORPUS N\u00ba 157784 &#8211; RJ (2021\/0382757-8)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Cl\u00e1udio Pereira Ramos N\u00e3o h\u00e1 um t\u00edtulo ou par\u00e1grafo introdut\u00f3rio que situe o leitor sobre o que esperar, portanto n\u00e3o sabemos de que se trata e ca\u00edmos direto no texto, sobre uma senten\u00e7a n\u00e3o conhecida. Os recorrentes, que s\u00e3o policiais, entraram com recurso contra o ac\u00f3rd\u00e3o do Tribunal de Justi\u00e7a do Rio de Janeiro [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[282,283,229,30],"coauthors":[],"class_list":["post-536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-direito-processual-penal","tag-inquerito-policial","tag-interceptacao-telefonica","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=536"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/536\/revisions"}],"predecessor-version":[{"id":538,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/536\/revisions\/538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/537"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=536"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}