{"id":545,"date":"2022-05-30T12:07:49","date_gmt":"2022-05-30T15:07:49","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=545"},"modified":"2022-05-30T12:07:49","modified_gmt":"2022-05-30T15:07:49","slug":"stj-lei-14-555-2021-so-alterou-competencia-para-julgamento-de-estelionato-em-casos-especificos","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-lei-14-555-2021-so-alterou-competencia-para-julgamento-de-estelionato-em-casos-especificos\/","title":{"rendered":"STJ: Lei 14.555\/2021 s\u00f3 alterou compet\u00eancia para julgamento de estelionato em casos espec\u00edficos"},"content":{"rendered":"<p>A Terceira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ), por unanimidade, entendeu que no crime de estelionato, n\u00e3o havendo as hip\u00f3teses descritas no <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/del3689.htm#art70\" target=\"_blank\" rel=\"noopener\"><strong>par\u00e1grafo 4\u00ba do artigo 70 do C\u00f3digo de Processo Penal (CPP)<\/strong><\/a>, a compet\u00eancia para julgamento deve ser fixada no local onde o agente obteve, mediante fraude, em benef\u00edcio pr\u00f3prio ou de terceiros, os servi\u00e7os custeados pela v\u00edtima.<\/p>\n<p>Segundo o dispositivo, alterado pela Lei 14.155\/2021, nos crimes de estelionato praticados mediante dep\u00f3sito, emiss\u00e3o de cheques sem fundos ou com o pagamento frustrado, ou mediante transfer\u00eancia de valores, a compet\u00eancia ser\u00e1 definida pelo local do domic\u00edlio da v\u00edtima e, em caso de pluralidade de v\u00edtimas, ser\u00e1 fixada pela <span class=\"termo-glossario\" data-match=\"preven\u00e7\u00e3o\" data-termo=\"Preven\u00e7\u00e3o\" data-significado=\"Concorrendo dois ju\u00edzes igualmente competentes para um caso, fica prevento, ou seja, respons\u00e1vel pelo caso o primeiro a decidir sobre a mat\u00e9ria.\">preven\u00e7\u00e3o<\/span>.<\/p>\n<p>A decis\u00e3o veio ap\u00f3s o colegiado analisar <span class=\"termo-glossario\" data-match=\"conflito de compet\u00eancia\" data-termo=\"Conflito de Compet\u00eancia\" data-significado=\"Conflito que se d\u00e1 entre autoridades judici\u00e1rias ante compet\u00eancias previstas no ordenamento jur\u00eddico.\">conflito de compet\u00eancia<\/span> instaurado entre a 4\u00aa Vara Criminal de Bras\u00edlia e o ju\u00edzo de direito criminal do Foro Central de Barra Funda, em S\u00e3o Paulo, nos autos de <span class=\"termo-glossario\" data-match=\"inqu\u00e9rito\" data-termo=\"Inqu\u00e9rito\" data-significado=\"Procedimento investigativo o qual inclui inqu\u00e9ritos policiais e os administrativos que possam resultar em responsabilidade penal, e que s\u00f3 passar\u00e3o \u00e0 classe A\u00e7\u00e3o Penal (APn) ap\u00f3s oferecimento da den\u00fancia ou queixa.\">inqu\u00e9rito<\/span> destinado a apurar estelionato contra uma empresa do ramo de turismo.<\/p>\n<p>Segundo as investiga\u00e7\u00f5es, um ex-funcion\u00e1rio teria simulado contratos de parceria com outras empresas para a compra de passagens a\u00e9reas \u2013 tanto para uso pr\u00f3prio quanto para repasse a terceiros \u2013 e para a reserva de ve\u00edculos e hot\u00e9is.<\/p>\n<p>A empresa de turismo fica em Bras\u00edlia, mas o ex-funcion\u00e1rio trabalhava na filial de S\u00e3o Paulo, onde os golpes teriam sido praticados com a ajuda de outros dois r\u00e9us, tamb\u00e9m residentes em munic\u00edpios paulistas.<\/p>\n<p><strong>Local onde a v\u00edtima sofreu preju\u00edzo ou local em que se consumou a infra\u00e7\u00e3o<\/strong><\/p>\n<p>Finalizadas as investiga\u00e7\u00f5es em S\u00e3o Paulo, o delegado representou ao ju\u00edzo estadual pelo envio dos autos \u00e0 Pol\u00edcia Civil do DF, sob o fundamento de que a empresa v\u00edtima tem sede na capital do pa\u00eds e \u00e9 correntista de ag\u00eancia banc\u00e1ria situada na mesma cidade.<\/p>\n<p>O Minist\u00e9rio P\u00fablico de S\u00e3o Paulo (MPSP) tamb\u00e9m se pronunciou pela remessa dos autos ao ju\u00edzo criminal do DF, mencionando precedentes da Terceira Se\u00e7\u00e3o do STJ no sentido de que o delito de estelionato pelo sistema banc\u00e1rio se consuma no local em que ocorre o efetivo preju\u00edzo \u00e0 v\u00edtima \u2013 ou seja, na localidade da ag\u00eancia onde a v\u00edtima possu\u00eda conta (<a href=\"https:\/\/processo.stj.jus.br\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=1452535&amp;num_registro=201502191773&amp;data=20151130&amp;formato=PDF\"><strong>CC 142.934<\/strong><\/a>, <a href=\"https:\/\/processo.stj.jus.br\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=1537689&amp;num_registro=201601943747&amp;data=20160919&amp;formato=PDF\"><strong>CC 147.811<\/strong><\/a> e <a href=\"https:\/\/processo.stj.jus.br\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=1515885&amp;num_registro=201502572320&amp;data=20160607&amp;formato=PDF\"><strong>CC 143.621<\/strong><\/a>).<\/p>\n<p>O ju\u00edzo paulista, acolhendo o parecer do MPSP, determinou a remessa do feito para o DF, cujo ju\u00edzo suscitou o conflito, sob o argumento de que a compet\u00eancia deve ser determinada pelo lugar em que se consumou a infra\u00e7\u00e3o. Segundo o ju\u00edzo do DF, a Lei 14.155\/2021 fez altera\u00e7\u00f5es na compet\u00eancia apenas em rela\u00e7\u00e3o aos casos de &#8220;estelionato eletr\u00f4nico&#8221;, mas o <span class=\"termo-intermed\" data-match=\"inqu\u00e9rito\">inqu\u00e9rito<\/span> envolvia hip\u00f3tese de crime praticado em seu modo cl\u00e1ssico.<\/p>\n<p><strong>Lei 14.155\/2021 eliminou controv\u00e9rsia sobre compet\u00eancia para julgar estelionato<\/strong><\/p>\n<p>Relator do processo no STJ, o ministro Joel Ilan Paciornik destacou que o tribunal j\u00e1 enfrentou diverg\u00eancias relativas \u00e0 compet\u00eancia para julgar crimes de estelionato, especialmente os praticados mediante transfer\u00eancias e dep\u00f3sitos banc\u00e1rios \u2013 modalidade cada vez mais frequente em raz\u00e3o do aumento de compras e outros neg\u00f3cios pela internet.<\/p>\n<p>Por\u00e9m, ele ressaltou que a controv\u00e9rsia levantada pelos ju\u00edzos envolvidos no <span class=\"termo-intermed\" data-match=\"conflito de compet\u00eancia\">conflito de compet\u00eancia<\/span> deixou de existir ap\u00f3s a edi\u00e7\u00e3o da Lei 14.155\/2021, pois ficou definido a quem cabe julgar o estelionato nas situa\u00e7\u00f5es espec\u00edficas descritas pelo legislador \u2013 as quais n\u00e3o ocorreram no caso em discuss\u00e3o, j\u00e1 que n\u00e3o h\u00e1 informa\u00e7\u00e3o sobre transfer\u00eancias banc\u00e1rias ou dep\u00f3sitos efetuados pela empresa v\u00edtima, nem sobre cheques sem fundos.<\/p>\n<p>De acordo com o ministro, a Terceira Se\u00e7\u00e3o do STJ decidiu recentemente que, nas situa\u00e7\u00f5es n\u00e3o contempladas pela nova lei, deve prevalecer a compet\u00eancia do ju\u00edzo do local do eventual dano.<\/p>\n<p>Dessa forma, o relator concluiu pela compet\u00eancia do ju\u00edzo de direito criminal do Foro Central de Barra Funda, visto que o estado de S\u00e3o Paulo foi o local em que o r\u00e9u obteve, mediante fraude, em benef\u00edcio pr\u00f3prio e de terceiros, os servi\u00e7os custeados pela v\u00edtima.<\/p>\n<p><strong>PROCESSO RELACIONADO:<\/strong><a href=\"https:\/\/processo.stj.jus.br\/processo\/julgamento\/eletronico\/documento\/mediado\/?documento_tipo=integra&amp;documento_sequencial=153376147&amp;registro_numero=202200372140&amp;peticao_numero=&amp;publicacao_data=20220513&amp;formato=PDF\" target=\"_blank\" rel=\"noopener\"><strong> CC 185.983<\/strong><\/a>.<\/p>\n<p><strong>FONTE:<\/strong> Com informa\u00e7\u00f5es da assessoria de comunica\u00e7\u00e3o social do STJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ), por unanimidade, entendeu que no crime de estelionato, n\u00e3o havendo as hip\u00f3teses descritas no par\u00e1grafo 4\u00ba do artigo 70 do C\u00f3digo de Processo Penal (CPP), a compet\u00eancia para julgamento deve ser fixada no local onde o agente obteve, mediante fraude, em benef\u00edcio pr\u00f3prio ou de terceiros, [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[286,282,280,30],"coauthors":[],"class_list":["post-545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-conflito-de-competencias","tag-direito-processual-penal","tag-estelionato","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"predecessor-version":[{"id":547,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/545\/revisions\/547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/546"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=545"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}