{"id":564,"date":"2022-06-07T22:45:38","date_gmt":"2022-06-08T01:45:38","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=564"},"modified":"2022-06-07T22:45:38","modified_gmt":"2022-06-08T01:45:38","slug":"stj-bem-de-familia-pode-ser-penhorado-por-divida-de-contrato-de-empreitada-global-para-construcao-do-imovel","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-bem-de-familia-pode-ser-penhorado-por-divida-de-contrato-de-empreitada-global-para-construcao-do-imovel\/","title":{"rendered":"STJ: Bem de fam\u00edlia pode ser penhorado por d\u00edvida de contrato de empreitada global para constru\u00e7\u00e3o do im\u00f3vel"},"content":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) definiu que se admite a penhora do bem de fam\u00edlia para saldar o d\u00e9bito originado de contrato de empreitada global celebrado para a constru\u00e7\u00e3o do pr\u00f3prio im\u00f3vel.<\/p>\n<p>A discuss\u00e3o surgiu na cobran\u00e7a de d\u00edvida originada de contrato firmado para a constru\u00e7\u00e3o do im\u00f3vel de resid\u00eancia dos devedores. O tribunal de segunda inst\u00e2ncia autorizou a penhora, entendendo que o caso se enquadra na exce\u00e7\u00e3o \u00e0 impenhorabilidade do bem de fam\u00edlia prevista no <a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l8009.htm#art3\" target=\"_blank\" rel=\"noopener\"><strong>artigo 3\u00ba, II, da Lei 8.009\/1990<\/strong><\/a> (d\u00edvida relacionada ao financiamento).<\/p>\n<p>Os devedores alegaram que, sendo exce\u00e7\u00e3o \u00e0 prote\u00e7\u00e3o legal da moradia, o dispositivo deveria ser interpretado restritivamente, alcan\u00e7ando apenas o titular do cr\u00e9dito decorrente do financiamento, ou seja, o agente financeiro. Isso excluiria o empreiteiro que fez a obra e ficou de receber diretamente do propriet\u00e1rio.<\/p>\n<p><strong>Prote\u00e7\u00e3o especial do bem de fam\u00edlia n\u00e3o \u00e9 absoluta<\/strong><\/p>\n<p>Relatora do processo no STJ, a ministra Nancy Andrighi lembrou que o bem de fam\u00edlia recebe especial prote\u00e7\u00e3o do ordenamento jur\u00eddico. No entanto, ela observou que a impenhorabilidade n\u00e3o \u00e9 absoluta, de forma que a pr\u00f3pria lei estabeleceu diversas exce\u00e7\u00f5es a essa prote\u00e7\u00e3o \u2013 entre elas, a hip\u00f3tese em que a a\u00e7\u00e3o \u00e9 movida para cobran\u00e7a de d\u00edvida decorrente de financiamento para constru\u00e7\u00e3o ou compra de im\u00f3vel.<\/p>\n<p>A magistrada destacou que as hip\u00f3teses de exce\u00e7\u00e3o, por restringirem a ampla prote\u00e7\u00e3o conferida ao im\u00f3vel familiar, devem ser interpretadas de forma restritiva, conforme entendimento j\u00e1 firmado pela Terceira e pela Quarta Turma do STJ.<\/p>\n<p>&#8220;N\u00e3o significa, todavia, que o julgador, no exerc\u00edcio de interpreta\u00e7\u00e3o do texto, fica restrito \u00e0 letra da lei. Ao interpretar a norma, incumbe ao int\u00e9rprete identificar a <em><span class=\"termo-glossario\" data-match=\"mens legis\" data-termo=\"Mens legis\" data-significado=\"O esp\u00edrito ou a finalidade da lei.\">mens legis<\/span><\/em>, isto \u00e9, o que o legislador desejaria se estivesse vivenciando a situa\u00e7\u00e3o analisada&#8221;, afirmou.<\/p>\n<p><strong>Legislador se preocupou em evitar deturpa\u00e7\u00e3o do objetivo da Lei 8.009\/1990<\/strong><\/p>\n<p>No caso analisado, a relatora ponderou que h\u00e1 a peculiaridade de ser a d\u00edvida relativa a contrato de empreitada global, segundo o qual o empreiteiro se obriga a construir a obra e a fornecer os materiais.<\/p>\n<p>Nancy Andrighi salientou que o STJ j\u00e1 se manifestou no sentido de que a exce\u00e7\u00e3o do artigo 3\u00ba, II, da Lei 8.009\/1990 se aplica \u00e0 d\u00edvida oriunda do contrato de compra e venda do im\u00f3vel e \u00e0 contra\u00edda para aquisi\u00e7\u00e3o do terreno onde o devedor edificou, com recursos pr\u00f3prios, a casa que serve de resid\u00eancia da fam\u00edlia.<\/p>\n<p>Al\u00e9m disso, citou precedente em que a Quarta Turma, ao enfrentar quest\u00e3o semelhante (<a href=\"https:\/\/processo.stj.jus.br\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=1877427&amp;num_registro=201001992957&amp;data=20191021&amp;formato=PDF\"><strong>REsp 1.221.372<\/strong><\/a>), entendeu que a palavra &#8220;financiamento&#8221;, inserida no inciso II do artigo 3\u00ba da Lei 8.009\/1990, n\u00e3o restringiu a impenhorabilidade \u00e0s situa\u00e7\u00f5es de compra ou constru\u00e7\u00e3o com recursos de agentes financiadores.<\/p>\n<p>&#8220;\u00c9 n\u00edtida a preocupa\u00e7\u00e3o do legislador no sentido de impedir a deturpa\u00e7\u00e3o do benef\u00edcio legal, vindo a ser utilizado como artif\u00edcio para viabilizar aquisi\u00e7\u00e3o, melhoramento, uso, gozo e\/ou disposi\u00e7\u00e3o do bem de fam\u00edlia sem nenhuma contrapartida, \u00e0 custa de terceiros&#8221;, declarou a ministra.<\/p>\n<p>&#8220;Portanto, a d\u00edvida relativa a contrato de empreitada global, porque viabiliza a constru\u00e7\u00e3o do im\u00f3vel, est\u00e1 abrangida pela exce\u00e7\u00e3o prevista no artigo 3\u00ba, II, da Lei n\u00ba 8.009\/1990&#8221;, concluiu.<\/p>\n<p><strong>PROCESSO RELACIONADO<\/strong>: <a href=\"https:\/\/processo.stj.jus.br\/processo\/revista\/documento\/mediado\/?componente=ITA&amp;sequencial=2143484&amp;num_registro=202102511415&amp;data=20220311&amp;formato=PDF\" target=\"_blank\" rel=\"noopener\"><strong>REsp 1.976.743<\/strong><\/a>.<\/p>\n<p><strong>FONTE:<\/strong> Com informa\u00e7\u00f5es da assessoria de comunica\u00e7\u00e3o social do STJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Turma do Superior Tribunal de Justi\u00e7a (STJ) definiu que se admite a penhora do bem de fam\u00edlia para saldar o d\u00e9bito originado de contrato de empreitada global celebrado para a constru\u00e7\u00e3o do pr\u00f3prio im\u00f3vel. A discuss\u00e3o surgiu na cobran\u00e7a de d\u00edvida originada de contrato firmado para a constru\u00e7\u00e3o do im\u00f3vel de resid\u00eancia dos [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[300,301,30],"coauthors":[],"class_list":["post-564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-bem-de-familia","tag-empreitada-global","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=564"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/564\/revisions"}],"predecessor-version":[{"id":566,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/564\/revisions\/566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/565"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=564"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}