{"id":627,"date":"2022-07-19T15:50:51","date_gmt":"2022-07-19T18:50:51","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=627"},"modified":"2022-07-19T15:50:51","modified_gmt":"2022-07-19T18:50:51","slug":"trf-3-juizado-especial-federal-itinerante-como-pratica-juridica-e-tema-de-palestra-para-estudantes-de-direito-da-ufms","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/trf-3-juizado-especial-federal-itinerante-como-pratica-juridica-e-tema-de-palestra-para-estudantes-de-direito-da-ufms\/","title":{"rendered":"TRF-3: Juizado Especial Federal Itinerante como Pr\u00e1tica Jur\u00eddica\u201d \u00e9 tema de palestra para estudantes de Direito da UFMS"},"content":{"rendered":"<p>\u201cA pr\u00e1tica jur\u00eddica vai muito al\u00e9m do conhecimento t\u00e9cnico para fazer uma boa peti\u00e7\u00e3o, contesta\u00e7\u00e3o ou senten\u00e7a. \u00c9 preciso ter empatia para compreender as pessoas e suas necessidades.\u201d<\/p>\n<p>Com essas palavras, a presidente do Tribunal Regional Federal da 3\u00aa Regi\u00e3o (TRF3) iniciou a palestra \u201cJuizado Especial Federal Itinerante como Pr\u00e1tica Jur\u00eddica\u201d, no audit\u00f3rio da Se\u00e7\u00e3o Judici\u00e1ria de Mato Grosso do Sul, na \u00faltima quarta-feira (13\/7), em Campo Grande\/MS.<\/p>\n<p>Na plateia, rostos jovens. Em sua maioria, estudantes de Direito da Universidade Federal do Mato Grosso do Sul (UFMS), incluindo alunos das unidades de Coxim e Corumb\u00e1, que viajaram \u00e0 capital sul-mato-grossense em grupos organizados por professores.<\/p>\n<p>Gra\u00e7as \u00e0 parceria entre a Justi\u00e7a Federal e a UFMS, alunos da Faculdade de Direito atuaram no atendimento com orienta\u00e7\u00f5es jur\u00eddicas aos jurisdicionados no Juizado Itinerante em Corumb\u00e1, realizado em novembro de 2021 e abril deste ano. Eles participar\u00e3o, tamb\u00e9m, da pr\u00f3xima edi\u00e7\u00e3o, em Coxim, de 25 a 29 de julho.<\/p>\n<p>Antes de abordar diretamente o JEF Itinerante, a presidente fez um hist\u00f3rico da cria\u00e7\u00e3o dos Juizados Especiais Federais (JEFs), que completaram 20 anos em 2022. Segundo a magistrada, os JEFs promoveram uma revolu\u00e7\u00e3o na Justi\u00e7a Federal e colocaram os magistrados em contato direto com a vida de pessoas vulner\u00e1veis. \u201cFoi um choque de realidade\u201d, recordou.<\/p>\n<p>Gra\u00e7as \u00e0 parceria entre a Justi\u00e7a Federal e a UFMS, alunos da Faculdade de Direito atuaram no atendimento com orienta\u00e7\u00f5es jur\u00eddicas aos jurisdicionados no Juizado Itinerante em Corumb\u00e1, realizado em novembro de 2021 e abril deste ano. Eles participar\u00e3o, tamb\u00e9m, da pr\u00f3xima edi\u00e7\u00e3o, em Coxim, de 25 a 29 de julho.<\/p>\n<p>Antes de abordar diretamente o JEF Itinerante, a presidente fez um hist\u00f3rico da cria\u00e7\u00e3o dos Juizados Especiais Federais (JEFs), que completaram 20 anos em 2022. Segundo a magistrada, os JEFs promoveram uma revolu\u00e7\u00e3o na Justi\u00e7a Federal e colocaram os magistrados em contato direto com a vida de pessoas vulner\u00e1veis. \u201cFoi um choque de realidade\u201d, recordou.<\/p>\n<p>\u201cAt\u00e9 ent\u00e3o, a Justi\u00e7a Federal lidava majoritariamente com processos de pessoas ricas, empres\u00e1rios, bancos. Nos juizados, passamos a ver o Direito na sua forma concreta, havia contato com as pessoas. As partes tinham um rosto, uma cara\u201d, destacou.<\/p>\n<p>A magistrada, que \u00e9 autora de obras de Direito Previdenci\u00e1rio, contou que, at\u00e9 a cria\u00e7\u00e3o dos Juizados, havia pouca aten\u00e7\u00e3o \u00e0 \u00e1rea. \u201cQuase toda bibliografia relevante sobre Direito Previdenci\u00e1rio foi produzida ap\u00f3s 2002.\u201d<\/p>\n<p>Ela destacou que os JEFs da 3\u00aa Regi\u00e3o j\u00e1 nasceram digitais, algo impens\u00e1vel \u00e0 \u00e9poca. \u201cO sistema foi inteiramente criado por servidores, sem custos adicionais, a partir das ideias dos magistrados\u201d. Mais do que uma proposta arrojada, a cria\u00e7\u00e3o de uma Justi\u00e7a sem papel era uma necessidade diante da escassez de recursos.<\/p>\n<p>A tecnologia, no entanto, n\u00e3o substitui o contato humano. Para a magistrada, por mais que hoje o Judici\u00e1rio tenha avan\u00e7ado muito na digitaliza\u00e7\u00e3o dos processos, o atendimento presencial \u00e9 indispens\u00e1vel. \u201cN\u00e3o \u00e9 todo mundo que tem inclus\u00e3o digital\u201d, pontuou.<\/p>\n<p>Para Marisa Santos, al\u00e9m do atendimento nas varas, a realiza\u00e7\u00e3o de projetos como o JEF Itinerante \u00e9 essencial. \u201cMuitas vezes, as mesmas pessoas que n\u00e3o t\u00eam condi\u00e7\u00f5es de acompanhar os processos pela internet s\u00e3o as que n\u00e3o conseguem ir at\u00e9 os f\u00f3runs\u201d, ressaltou.<\/p>\n<p>Ela relembrou experi\u00eancias enfrentadas em juizados itinerantes por todo o pa\u00eds, na busca pela garantia de direitos dos mais vulner\u00e1veis em localidades remotas. \u201cH\u00e1 muitas coisas que a Justi\u00e7a n\u00e3o pode resolver. Falta pol\u00edtica p\u00fablica. O que podemos fazer \u00e9 ir at\u00e9 essa parcela da popula\u00e7\u00e3o\u201d, ponderou.<\/p>\n<p>Ao final, lembrou aos estudantes que, em um pa\u00eds como o Brasil, nem todos t\u00eam oportunidades de qualifica\u00e7\u00e3o. \u201cN\u00f3s, que temos condi\u00e7\u00f5es de estudar, de estar hoje aqui em um lugar agrad\u00e1vel, acompanhando uma palestra, que tivemos fam\u00edlias que nos propiciaram tudo isso, somos privilegiados\u201d. Segundo a magistrada, a participa\u00e7\u00e3o em a\u00e7\u00f5es como o JEF Itinerante \u00e9 uma forma de retribui\u00e7\u00e3o dos estudantes \u00e0 sociedade.<\/p>\n<p><strong>Mesa<\/strong><\/p>\n<p>A mesa do evento foi presidida pelo desembargador federal Newton de Lucca. O magistrado, que \u00e9 professor da Faculdade de Direito da Universidade de S\u00e3o Paulo, agradeceu mais uma vez \u00e0 presidente do TRF3 pela oportunidade de retornar a Mato Grosso do Sul e, tamb\u00e9m, por participar do evento com os estudantes. \u201cA conviv\u00eancia com os mais jovens \u00e9 que me faz acreditar que vale a pena seguir em frente\u201d, declarou.<\/p>\n<p>A diretora do Foro da Se\u00e7\u00e3o Judici\u00e1ria de Mato Grosso do Sul, ju\u00edza federal Monique Marchioli Leite, mostrou-se emocionada com a realiza\u00e7\u00e3o do evento. \u201cQuando eu estudava para concurso, anos atr\u00e1s, aprendia Direito Previdenci\u00e1rio com os livros da Dra. Marisa Santos. \u00c0quela \u00e9poca, jamais imaginaria que estar\u00edamos aqui hoje.&#8221;<\/p>\n<p>O professor Aur\u00e9lio Briltes, que coordena o Escrit\u00f3rio Modelo de Assist\u00eancia Jur\u00eddica da Faculdade de Direito da UFMS, parabenizou a presidente pela palestra e declarou que as atividades de seus alunos no JEF Itinerante s\u00e3o \u201cuma quebra de paradigma na forma\u00e7\u00e3o do curso de Direito\u201d.<\/p>\n<p>FONTE: Com informa\u00e7\u00f5es da Assessoria de Comunica\u00e7\u00e3o Social do TRF-3<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cA pr\u00e1tica jur\u00eddica vai muito al\u00e9m do conhecimento t\u00e9cnico para fazer uma boa peti\u00e7\u00e3o, contesta\u00e7\u00e3o ou senten\u00e7a. \u00c9 preciso ter empatia para compreender as pessoas e suas necessidades.\u201d Com essas palavras, a presidente do Tribunal Regional Federal da 3\u00aa Regi\u00e3o (TRF3) iniciou a palestra \u201cJuizado Especial Federal Itinerante como Pr\u00e1tica Jur\u00eddica\u201d, no audit\u00f3rio da Se\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":628,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[352,351,29],"coauthors":[],"class_list":["post-627","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-emaj-itinerante","tag-palestra","tag-trf-3"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=627"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/627\/revisions"}],"predecessor-version":[{"id":629,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/627\/revisions\/629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/628"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=627"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}