{"id":749,"date":"2022-09-19T23:06:52","date_gmt":"2022-09-20T02:06:52","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=749"},"modified":"2022-09-19T23:06:52","modified_gmt":"2022-09-20T02:06:52","slug":"stj-responsabilizacao-penal-de-empresa-nao-e-transferida-com-incorporacao","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/stj-responsabilizacao-penal-de-empresa-nao-e-transferida-com-incorporacao\/","title":{"rendered":"STJ: Responsabiliza\u00e7\u00e3o penal de empresa n\u00e3o \u00e9 transferida com incorpora\u00e7\u00e3o"},"content":{"rendered":"<div id=\"corpoDaNoticiaBox\" class=\"conteudo_texto\">\n<div id=\"ctl00_PlaceHolderMain_ctl05__ControlWrapper_RichHtmlField\" class=\"ms-rtestate-field\" aria-labelledby=\"ctl00_PlaceHolderMain_ctl05_label\">\n<p>A Terceira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ), por maioria, decidiu que a responsabiliza\u00e7\u00e3o penal de empresa incorporada n\u00e3o pode ser transferida \u00e0 sociedade incorporadora. O colegiado fixou o entendimento de que o princ\u00edpio da intranscend\u00eancia da pena, previsto no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/constituicao\/constituicao.htm#art5xlv\" target=\"_blank\" rel=\"noopener\"><strong>artigo 5\u00ba, inciso XLV, da Constitui\u00e7\u00e3o Federal<\/strong><\/a>, pode ser aplicado \u00e0s pessoas jur\u00eddicas.<\/p>\n<p>De acordo com o processo, o Minist\u00e9rio P\u00fablico do Paran\u00e1 ofereceu den\u00fancia contra uma sociedade empres\u00e1ria agr\u00edcola, imputando-lhe a pr\u00e1tica do delito previsto no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l9605.htm#art54\" target=\"_blank\" rel=\"noopener\"><strong>artigo 54, par\u00e1grafo 2\u00ba, inciso V, da Lei 9.605\/1998<\/strong><\/a>, pelo suposto descarte de res\u00edduos s\u00f3lidos em desconformidade com as exig\u00eancias da legisla\u00e7\u00e3o estadual. A controv\u00e9rsia que chegou ao STJ diz respeito ao fato de a empresa acusada originariamente ter sido incorporada por outra.<\/p>\n<p>Ap\u00f3s a decis\u00e3o que rejeitou as preliminares da defesa, a empresa incorporadora impetrou <span class=\"termo-glossario\" data-match=\"mandado de seguran\u00e7a\" data-termo=\"Mandado de Seguran\u00e7a\" data-significado=\"A\u00e7\u00e3o prevista constitucionalmente para proteger direito l\u00edquido e certo, n\u00e3o amparado por &quot;habeas-corpus&quot; ou &quot;habeas-data&quot;, quando o respons\u00e1vel pela ilegalidade ou abuso de poder for autoridade p\u00fablica ou agente de pessoa jur\u00eddica no exerc\u00edcio de atribui\u00e7\u00f5es do Poder P\u00fablico;\">mandado de seguran\u00e7a<\/span>, alegando a extin\u00e7\u00e3o da punibilidade diante do encerramento da personalidade jur\u00eddica da r\u00e9 origin\u00e1ria da <span class=\"termo-glossario\" data-match=\"a\u00e7\u00e3o penal\" data-termo=\"A\u00e7\u00e3o Penal\" data-significado=\"A\u00e7\u00e3o penal (sigla APn) \u00e9 o processo em que se discute a ocorr\u00eancia e a autoria de crime. Pode ser p\u00fablica (proposta pelo Minist\u00e9rio P\u00fablico, diante do interesse da sociedade na puni\u00e7\u00e3o do criminoso) ou privada (proposta pela pr\u00f3pria v\u00edtima, nos casos de ofensa a interesse exclusivamente particular).\">a\u00e7\u00e3o penal<\/span> \u2013 a sociedade empresarial agr\u00edcola. Assim, por aplica\u00e7\u00e3o anal\u00f3gica do <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/decreto-lei\/del2848.htm#art107\" target=\"_blank\" rel=\"noopener\"><strong>artigo 107, inciso I, do C\u00f3digo Penal (CP)<\/strong><\/a>, que trata da morte do r\u00e9u, seria invi\u00e1vel o prosseguimento da a\u00e7\u00e3o contra a incorporadora. O Tribunal de Justi\u00e7a do Paran\u00e1 concedeu a seguran\u00e7a.<\/p>\n<p>No recurso encaminhado ao STJ, o Minist\u00e9rio P\u00fablico sustentou que tanto o princ\u00edpio da intranscend\u00eancia da pena como o artigo 107, inciso I, do CP t\u00eam incid\u00eancia restrita \u00e0s pessoas naturais, \u00fanicas capazes de morrer, sobretudo porque as penas patrimoniais previstas na Lei 9.605\/1998 poderiam ser assumidas pela incorporadora.<\/p>\n<p><strong>Pretens\u00e3o punitiva estatal n\u00e3o se confunde com obriga\u00e7\u00f5es transmiss\u00edveis<\/strong><\/p>\n<p>O relator do recurso, ministro Ribeiro Dantas, observou que a incorpora\u00e7\u00e3o \u00e9 uma opera\u00e7\u00e3o societ\u00e1ria t\u00edpica, por meio da qual apenas a sociedade empres\u00e1ria incorporadora continuar\u00e1 a existir, na qualidade de sucessora de todas as rela\u00e7\u00f5es patrimoniais da incorporada, cuja personalidade jur\u00eddica \u00e9 extinta.<\/p>\n<p>O magistrado apontou que a sucess\u00e3o da incorporada pela incorporadora se opera quanto a direitos e obriga\u00e7\u00f5es compat\u00edveis com a natureza da incorpora\u00e7\u00e3o, conforme se conclui a partir dos artigos <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/2002\/l10406.htm#art1116\" target=\"_blank\" rel=\"noopener\"><strong>1.116 do C\u00f3digo Civil<\/strong><\/a> e <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/leis\/l6404consol.htm#art227\" target=\"_blank\" rel=\"noopener\"><strong>227 da Lei 6.404\/1976<\/strong><\/a>.<\/p>\n<p>&#8220;A pretens\u00e3o punitiva estatal n\u00e3o se enquadra no conceito jur\u00eddico-dogm\u00e1tico de obriga\u00e7\u00e3o patrimonial transmiss\u00edvel, tampouco se confunde com o direito \u00e0 repara\u00e7\u00e3o civil dos danos causados ao meio ambiente. Logo, n\u00e3o h\u00e1 norma que autorize a transfer\u00eancia da responsabilidade penal \u00e0 incorporadora&#8221;, declarou Ribeiro Dantas.<\/p>\n<p><strong>Princ\u00edpio da intranscend\u00eancia da pena vale tamb\u00e9m para pessoas jur\u00eddicas<\/strong><\/p>\n<p>Para o relator, a extin\u00e7\u00e3o legal da pessoa jur\u00eddica r\u00e9 \u2013 sem nenhum ind\u00edcio de fraude \u2013 leva \u00e0 aplica\u00e7\u00e3o anal\u00f3gica do artigo 107, inciso I, do CP, com o consequente t\u00e9rmino da punibilidade.<\/p>\n<p>O ministro destacou, ainda, que o princ\u00edpio da intranscend\u00eancia da pena pode ser aplicado \u00e0s pessoas jur\u00eddicas, o que refor\u00e7a a tese de que a empresa incorporadora n\u00e3o deve ser responsabilizada penalmente pelos crimes da incorporada.<\/p>\n<p>&#8220;Se o direito penal brasileiro optou por permitir a responsabiliza\u00e7\u00e3o criminal dos entes coletivos, mesmo com as peculiaridades decorrentes da aus\u00eancia de um corpo biol\u00f3gico, n\u00e3o pode ser negada a eles a aplica\u00e7\u00e3o de garantias fundamentais utilizando-se dessas mesmas peculiaridades como argumento&#8221;, concluiu o relator ao negar <span class=\"termo-glossario\" data-match=\"provimento\" data-termo=\"Provimento\" data-significado=\"Ato de prover. Dar provimento a recurso significa acolher o pedido para reformar ou anular decis\u00e3o judicial anterior. No direito administrativo, \u00e9 o ato de preencher vaga no servi\u00e7o p\u00fablico.\">provimento<\/span> ao <span class=\"termo-glossario\" data-match=\"recurso especial\" data-termo=\"Recurso Especial\" data-significado=\"O recurso especial (sigla REsp) \u00e9 dirigido ao STJ para contestar poss\u00edvel m\u00e1 aplica\u00e7\u00e3o da lei federal por um tribunal de segundo grau. Assim, o REsp serve para que o STJ uniformize a interpreta\u00e7\u00e3o da legisla\u00e7\u00e3o federal em todo o pa\u00eds.\">recurso especial<\/span> do Minist\u00e9rio P\u00fablico.<\/p>\n<\/div>\n<\/div>\n<div id=\"pstj_elContProcessosRelacionados\" class=\"obj_texto_label_processos\"><span class=\"texto\"><strong>PROCESSO RELACIONADO<\/strong><span class=\"destaque\">: <\/span><\/span> <span id=\"pstj_elContItensProcessosRelacionados\" class=\"obj_textos_rel_processos\"> <a class=\"\" href=\"https:\/\/ww2.stj.jus.br\/processo\/pesquisa\/?aplicacao=processos.ea&amp;tipoPesquisa=tipoPesquisaGenerica&amp;termo=REsp 1977172\" target=\"janela_processos\" rel=\"noopener\">REsp 1977172<\/a><\/span><\/div>\n<div><strong>FONTE<\/strong>: Com informa\u00e7\u00f5es da Assessoria de Comunica\u00e7\u00e3o Social do STJ<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Terceira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a (STJ), por maioria, decidiu que a responsabiliza\u00e7\u00e3o penal de empresa incorporada n\u00e3o pode ser transferida \u00e0 sociedade incorporadora. O colegiado fixou o entendimento de que o princ\u00edpio da intranscend\u00eancia da pena, previsto no artigo 5\u00ba, inciso XLV, da Constitui\u00e7\u00e3o Federal, pode ser aplicado \u00e0s pessoas jur\u00eddicas. De [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":581,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[9,422,424,423,30],"coauthors":[],"class_list":["post-749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-direito-penal","tag-intranscendencia","tag-pena","tag-pessoa-juridica","tag-stj"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=749"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/749\/revisions"}],"predecessor-version":[{"id":750,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/749\/revisions\/750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/581"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=749"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}