{"id":950,"date":"2023-01-30T18:16:24","date_gmt":"2023-01-30T21:16:24","guid":{"rendered":"https:\/\/boletimjuridico.ufms.br\/?p=950"},"modified":"2023-01-30T18:16:24","modified_gmt":"2023-01-30T21:16:24","slug":"tst-e-devida-indenizacao-por-ter-sido-demissao-antes-do-termino-de-processo-disciplinar","status":"publish","type":"post","link":"https:\/\/boletimjuridico.ufms.br\/en\/tst-e-devida-indenizacao-por-ter-sido-demissao-antes-do-termino-de-processo-disciplinar\/","title":{"rendered":"TST: \u00c9 devida indeniza\u00e7\u00e3o por ter sido demiss\u00e3o antes do t\u00e9rmino de processo disciplinar"},"content":{"rendered":"<p>A Sexta Turma do Tribunal Superior do Trabalho reconheceu o direito de uma empregada da Caixa Econ\u00f4mica Federal a receber indeniza\u00e7\u00e3o por danos morais por ter sido dispensada por justa causa antes do processo disciplinar ser conclu\u00eddo.<\/p>\n<p>O colegiado entendeu, de forma un\u00e2nime, que houve precipita\u00e7\u00e3o do empregador no momento da aplica\u00e7\u00e3o da justa causa e restabeleceu a senten\u00e7a da 1\u00aa Vara do Trabalho de Guarapuava (PR), que condenou o banco ao pagamento da indeniza\u00e7\u00e3o. Por\u00e9m, o valor foi revisado passando dos R$ 150 mil arbitrado pelo ju\u00edzo de 1\u00ba grau para R$ 75 mil.<\/p>\n<p><strong>Demiss\u00e3o e reintegra\u00e7\u00e3o<\/strong><\/p>\n<p>A banc\u00e1ria, que trabalhava h\u00e1 33 anos na institui\u00e7\u00e3o, foi demitida ao longo de um processo disciplinar que apurava o desaparecimento de cerca de R$ 11 mil. Durante a investiga\u00e7\u00e3o, a comiss\u00e3o respons\u00e1vel concluiu que a trabalhadora havia agido com dolo e m\u00e1-f\u00e9, ficando sujeita \u00e0 pena de demiss\u00e3o por justa causa. Ap\u00f3s recurso durante o PAD, a pena foi reformada e a empregada reintegrada aos quadros do banco.<\/p>\n<p>A empregada permaneceu dois meses com o contrato rescindido. Ela relatou que, por morar em cidade pequena, o fato se tornou p\u00fablico, o que foi \u201cextremamente humilhante\u201d causando um dano moral de \u201cextrema gravidade\u201d.<\/p>\n<p>Mesmo ap\u00f3s a revers\u00e3o da justa causa, a banc\u00e1ria foi intimada a depor na Pol\u00edcia Federal, j\u00e1 que havia inqu\u00e9rito tramitando no \u00f3rg\u00e3o para a apura\u00e7\u00e3o das irregularidades. A Caixa n\u00e3o informou \u00e0 PF que a decis\u00e3o havia sido reformada.<\/p>\n<p><strong>Jurisprud\u00eancia\u00a0<\/strong><\/p>\n<p>O ju\u00edzo de primeiro grau julgou procedente o pedido da empregada para receber indeniza\u00e7\u00e3o por danos morais e o arbitrou em R$ 150 mil. Mas, ao analisar recurso, o Tribunal Regional do Trabalho da 6\u00aa Regi\u00e3o (PE) afastou a decis\u00e3o por considerar que a empresa reverteu a justa causa por iniciativa pr\u00f3pria, al\u00e9m de ter feito o procedimento investigat\u00f3rio em sigilo, conforme testemunhas disseram.<\/p>\n<p>Houve recurso de revista da banc\u00e1ria ao TST, e o relator na Sexta Turma, ministro Augusto C\u00e9sar, votou no sentido de restabelecer o pagamento da indeniza\u00e7\u00e3o por danos morais, contudo no valor de R$ 75 mil. De acordo com o ministro, a atitude da empresa causou constrangimento e humilha\u00e7\u00e3o. \u201cA conduta da reclamada foi precipitada, porque, em raz\u00e3o da gravidade da acusa\u00e7\u00e3o, a Caixa deveria, por cautela, ter aguardado a conclus\u00e3o do processo administrativo antes de aplicar a justa causa, evitando, assim, o constrangimento e a \u00a0humilha\u00e7\u00e3o injustamente impostos \u00e0 reclamante\u201d.<\/p>\n<p>O ministro, por\u00e9m, registrou que o valor de R$ 150 mil arbitrado na senten\u00e7a \u00e9 excessivo, frente \u00e0s circunst\u00e2ncias f\u00e1ticas do caso e \u00e0 jurisprud\u00eancia do TST em casos similares. \u201cDesse modo, levando-se em conta o dano, sua extens\u00e3o, a culpabilidade da r\u00e9 e a condi\u00e7\u00e3o econ\u00f4mica das partes, arbitro novo valor \u00e0 indeniza\u00e7\u00e3o por danos morais, no importe de R$75 mil\u201d.<\/p>\n<p>Por unanimidade, a Sexta Turma acompanhou o voto do relator, mas foram apresentados embargos de declara\u00e7\u00e3o, ainda n\u00e3o julgados.<\/p>\n<p><strong>PROCESSO RELACIONADO<\/strong>: <a href=\"https:\/\/consultaprocessual.tst.jus.br\/consultaProcessual\/consultaTstNumUnica.do?conscsjt=&amp;numeroTst=479&amp;digitoTst=97&amp;anoTst=2015&amp;orgaoTst=5&amp;tribunalTst=09&amp;varaTst=0096&amp;consulta=Consultar\" target=\"_blank\" rel=\"noopener\" data-senna-off=\"true\">RR 479-97.2015.5.09.0096<\/a><\/p>\n<p><strong>FONTE<\/strong>: Com informa\u00e7\u00f5es da Se\u00e7\u00e3o de Comunica\u00e7\u00e3o Social do TST<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Sexta Turma do Tribunal Superior do Trabalho reconheceu o direito de uma empregada da Caixa Econ\u00f4mica Federal a receber indeniza\u00e7\u00e3o por danos morais por ter sido dispensada por justa causa antes do processo disciplinar ser conclu\u00eddo. O colegiado entendeu, de forma un\u00e2nime, que houve precipita\u00e7\u00e3o do empregador no momento da aplica\u00e7\u00e3o da justa causa [&hellip;]<\/p>\n","protected":false},"author":41226,"featured_media":612,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[83,529,64],"coauthors":[],"class_list":["post-950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-indenizacao","tag-processo-disciplinar","tag-tst"],"_links":{"self":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/users\/41226"}],"replies":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/comments?post=950"}],"version-history":[{"count":1,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/950\/revisions"}],"predecessor-version":[{"id":951,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/posts\/950\/revisions\/951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media\/612"}],"wp:attachment":[{"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/media?parent=950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/categories?post=950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/tags?post=950"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/boletimjuridico.ufms.br\/en\/wp-json\/wp\/v2\/coauthors?post=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}